{"id":22930,"date":"2020-05-28T13:04:53","date_gmt":"2020-05-28T11:04:53","guid":{"rendered":"https:\/\/ddoptics.shop\/?post_type=glossary&#038;p=22930"},"modified":"2020-05-28T13:07:53","modified_gmt":"2020-05-28T11:07:53","slug":"comparacion-prisma-de-techo-porro","status":"publish","type":"glossary","link":"https:\/\/ddoptics.shop\/es\/fachwort\/vergleich-porro-dachkant-prisma\/","title":{"rendered":"Comparaci\u00f3n de prismas Porro y de techo"},"content":{"rendered":"<h2>Diferencia y comparaci\u00f3n entre porroprismas y prismas de techo<\/h2>\n<p>El dise\u00f1o de los prism\u00e1ticos siempre viene determinado por el tipo de prisma utilizado.<\/p>\n<figure id=\"attachment_8768\" aria-describedby=\"caption-attachment-8768\" style=\"width: 217px\" class=\"wp-caption alignright\"><img decoding=\"async\" class=\"wp-image-8768 size-full\" src=\"https:\/\/ddoptics.shop\/wp-content\/uploads\/2016\/06\/fernglaeser-arten.jpg\" alt=\"Sistemas de prismas binoculares\" width=\"217\" height=\"182\" title=\"\"><figcaption id=\"caption-attachment-8768\" class=\"wp-caption-text\">Diferencia entre sistemas de prismas izquierda: Prisma de techo, derecha: Porro<\/figcaption><\/figure>\n<h3>Prisma porro para prism\u00e1ticos<\/h3>\n<p>Invitados de larga distancia con el\u00a0<strong>Construcci\u00f3n de prisma porro<\/strong>\u00a0se reconoce por su altura relativamente baja y su dise\u00f1o ancho.\u00a0<strong>Ventaja:\u00a0<\/strong>La mayor distancia entre las dos lentes favorece la visi\u00f3n espacial. Una ilustraci\u00f3n gr\u00e1fica y m\u00e1s detalles sobre el\u00a0<strong>Construcci\u00f3n de porroprismas\u00a0<\/strong>\u00a1cons\u00edgalo aqu\u00ed!<\/p>\n<h3>Prisma de techo para prism\u00e1ticos<\/h3>\n<p>Gafas de larga distancia con\u00a0<strong>Prismas de techo<\/strong>\u00a0tienen un dise\u00f1o ligeramente m\u00e1s delgado y largo. Los prismas de techo son un dise\u00f1o m\u00e1s moderno con varios prismas rectificados con precisi\u00f3n, lo que hace m\u00e1s compleja la producci\u00f3n de lentes de prisma de techo.\u00a0<strong>Ventaja:<\/strong>\u00a0Las gafas de este dise\u00f1o son especialmente delgadas y f\u00e1ciles de manejar.<\/p>\n<p>Una representaci\u00f3n gr\u00e1fica y m\u00e1s detalles sobre la construcci\u00f3n de\u00a0<strong>Prismas de techo\u00a0<\/strong>recibir\u00e1s\u00a0<strong>aqu\u00ed<\/strong>\u00a1! Por regla general, no existe ninguna diferencia fundamental en la calidad del rendimiento \u00f3ptico entre ambos dise\u00f1os. La importancia y la finalidad de los prismas en \u00f3ptica es\u00a0<strong>aqu\u00ed<\/strong>\u00a0explicadas con m\u00e1s detalle.<\/p>","protected":false},"excerpt":{"rendered":"<p>Unterschied und Vergleich von Porroprismen zu Dachkantprismen Die Bauform des Fernglases wird immer durch die verwendete Prismenart bestimmt. Porro Prisma bei Ferngl\u00e4sern Ferng\u00e4ser mit der\u00a0Porroprismen Bauweise\u00a0erkennt man an der relativ geringen H\u00f6he mit breiter Bauform.\u00a0Vorteil:\u00a0Durch den gr\u00f6\u00dferen Abstand der beiden Objektive wird das r\u00e4umliche Sehen gef\u00f6rdert. Eine grafische Darstellung sowie weitere Details zur\u00a0Bauweise von Porroprismen\u00a0erhalten [&#8230;]\n","protected":false},"author":2,"featured_media":8883,"parent":0,"template":"","glossary-cat":[950],"class_list":["post-22930","glossary","type-glossary","status-publish","has-post-thumbnail","hentry","glossary-cat-optik-wiki"],"related_terms":"Unterschied,Vergleich","external_url":"","internal_reference_id":"","_links":{"self":[{"href":"https:\/\/ddoptics.shop\/es\/wp-json\/wp\/v2\/glossary\/22930","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ddoptics.shop\/es\/wp-json\/wp\/v2\/glossary"}],"about":[{"href":"https:\/\/ddoptics.shop\/es\/wp-json\/wp\/v2\/types\/glossary"}],"author":[{"embeddable":true,"href":"https:\/\/ddoptics.shop\/es\/wp-json\/wp\/v2\/users\/2"}],"version-history":[{"count":3,"href":"https:\/\/ddoptics.shop\/es\/wp-json\/wp\/v2\/glossary\/22930\/revisions"}],"predecessor-version":[{"id":22933,"href":"https:\/\/ddoptics.shop\/es\/wp-json\/wp\/v2\/glossary\/22930\/revisions\/22933"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ddoptics.shop\/es\/wp-json\/wp\/v2\/media\/8883"}],"wp:attachment":[{"href":"https:\/\/ddoptics.shop\/es\/wp-json\/wp\/v2\/media?parent=22930"}],"wp:term":[{"taxonomy":"glossary-cat","embeddable":true,"href":"https:\/\/ddoptics.shop\/es\/wp-json\/wp\/v2\/glossary-cat?post=22930"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}