{"id":26453,"date":"2023-04-11T16:45:20","date_gmt":"2023-04-11T14:45:20","guid":{"rendered":"https:\/\/ddoptics.shop\/?post_type=product&#038;p=26453"},"modified":"2025-03-16T10:31:54","modified_gmt":"2025-03-16T09:31:54","slug":"unic-carbon-shaft-winchester-sxr2","status":"publish","type":"product","link":"https:\/\/ddoptics.shop\/es\/kaufen\/unic-carbonschaft-winchester-sxr2\/","title":{"rendered":"Culata de carbono UNIC de FBT | para rifle Winchester SXR2"},"content":{"rendered":"<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_475088976\">\n\t\t<a class=\"image-lightbox lightbox-gallery\" title=\"\" href=\"https:\/\/ddoptics.shop\/wp-content\/uploads\/2023\/04\/Unic-Winchester-SXR2-neu.webp\">\t\t\t\t\t\t<div class=\"img-inner image-zoom dark\" >\n\t\t\t<img decoding=\"async\" width=\"1200\" height=\"250\" src=\"https:\/\/ddoptics.shop\/wp-content\/uploads\/2023\/04\/Unic-Winchester-SXR2-neu.webp\" class=\"attachment-original size-original\" alt=\"Culata de Carbono UNIC Winchester SXR2 | Fine Ballistic Tools\" srcset=\"https:\/\/ddoptics.shop\/wp-content\/uploads\/2023\/04\/Unic-Winchester-SXR2-neu.webp 1200w, https:\/\/ddoptics.shop\/wp-content\/uploads\/2023\/04\/Unic-Winchester-SXR2-neu-800x167.webp 800w, https:\/\/ddoptics.shop\/wp-content\/uploads\/2023\/04\/Unic-Winchester-SXR2-neu-304x63.webp 304w, https:\/\/ddoptics.shop\/wp-content\/uploads\/2023\/04\/Unic-Winchester-SXR2-neu-632x132.webp 632w, https:\/\/ddoptics.shop\/wp-content\/uploads\/2023\/04\/Unic-Winchester-SXR2-neu-305x64.webp 305w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" title=\"\">\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/a>\t\t\n<style>\n#image_475088976 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n<h2>CULATA UNIC DE CARBONO PARA RIFLE WINCHESTER SRX2 | FBT - FINE BALLISTIC TOOLS | \u00bfPREPARADO PARA UNA EXPERIENCIA DE TIRO DE SIGUIENTE NIVEL?<\/h2>\n<div class=\"row\"  id=\"row-665400984\">\n\n\t<div id=\"col-1706961575\" class=\"col medium-8 small-12 large-8\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<p>... o dicho de otro modo:\u00a0<strong>M\u00c1S<\/strong>\u00a0Ergonom\u00eda,\u00a0<strong>M\u00c1S<\/strong>\u00a0Precisi\u00f3n,\u00a0<strong>MENOS<\/strong> \u00a1Pesa con tu arma est\u00e1ndar!\u00a0<span style=\"background-color: #ffff00;\">No s\u00f3lo es posible para el Winchester SXR2 .... sino para todos los sistemas de armas del mundo.<\/span><\/p>\n<p>Cada vez m\u00e1s <strong>Tiradores y cazadores<\/strong> encuentran el moderno \"dise\u00f1o de fibra de carbono\" no s\u00f3lo extremadamente bello, sino tambi\u00e9n realmente bien adaptado a un concepto de arma visualmente exitoso y moderno - como el del arma Browning BAR MK1.<\/p>\n<h3>Browning BAR MK1 con culata UNIC - una combinaci\u00f3n exitosa<\/h3>\n<p>Equipa tu <a href=\"https:\/\/de.wikipedia.org\/wiki\/Winchester_Repeating_Arms_Company\" target=\"_blank\" rel=\"noopener sponsored\"><strong>Rifle Winchester SXR2<\/strong><\/a> ahora simplemente con el innovador <strong><a href=\"https:\/\/ddoptics.shop\/es\/eje-fbt-unic-carbono-eje-perforado\/\" target=\"_blank\" rel=\"noopener\" data-schema-attribute=\"\">Soluci\u00f3n del CINU<\/a> de FBT <\/strong>hacia arriba o hacia abajo. Con la nueva culata de fibra de carbono FBT UNIC, ultraligera y muy resistente, podr\u00e1 hacerlo en un abrir y cerrar de ojos.<\/p>\n<blockquote><p>Culatas de carbono: la deformaci\u00f3n en condiciones meteorol\u00f3gicas adversas es cosa del pasado. A cambio, el arma es mucho m\u00e1s ligera, tiene buen aspecto y reduce notablemente el retroceso.<\/p><\/blockquote>\n<p>A trav\u00e9s de la <strong>eje de carbono aprox. 650 g m\u00e1s ligero<\/strong> su Winchester SXR2<\/p>\n<p>Arma especialmente en el <strong>parada a mano alzada<\/strong> tienen un efecto positivo inmediato.<\/p>\n<figure id=\"attachment_24739\" aria-describedby=\"caption-attachment-24739\" style=\"width: 300px\" class=\"wp-caption alignleft\"><img decoding=\"async\" class=\"wp-image-24739\" src=\"https:\/\/ddoptics.shop\/wp-content\/uploads\/2021\/04\/Halder-Buchse-.jpg\" alt=\"Enganche de halc\u00f3n para eslingas giratorias &quot;Push &amp; Go&quot; de serie\" width=\"300\" height=\"200\" title=\"\" srcset=\"https:\/\/ddoptics.shop\/wp-content\/uploads\/2021\/04\/Halder-Buchse-.jpg 600w, https:\/\/ddoptics.shop\/wp-content\/uploads\/2021\/04\/Halder-Buchse--304x203.jpg 304w, https:\/\/ddoptics.shop\/wp-content\/uploads\/2021\/04\/Halder-Buchse--305x203.jpg 305w, https:\/\/ddoptics.shop\/wp-content\/uploads\/2021\/04\/Halder-Buchse--510x340.jpg 510w, https:\/\/ddoptics.shop\/wp-content\/uploads\/2021\/04\/Halder-Buchse--250x167.jpg 250w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><figcaption id=\"caption-attachment-24739\" class=\"wp-caption-text\">Casquillos Halder para eslingas giratorias \"Push &amp; Go\" (integrados de serie)<\/figcaption><\/figure>\n<p>Una caracter\u00edstica importante del <a href=\"https:\/\/fineballistictools.com\/carbonschaft\/unic-universal-carbon-stock\/\" target=\"_blank\" rel=\"noopener sponsored\" data-schema-attribute=\"\"><strong>Eje FBT UNIC<\/strong><\/a> es que el arma cambia sus propiedades en funci\u00f3n de los a\u00f1os de experiencia en la construcci\u00f3n de existencias, es decir. <strong>Top-heavy que mejora la precisi\u00f3n<\/strong> se convierte.<\/p>\n<p>En <strong>Precio atractivo<\/strong> en este <strong>Clase de eje de carbono<\/strong> es \u00fanico hasta la fecha y complacer\u00e1 a muchos nuevos propietarios de UNIC. Un eje de carbono de esta calidad suele costar m\u00e1s de 2.500 \u20ac.<\/p>\n<p>Este precio habitual podr\u00eda reducirse en<strong> Consideraciones sobre un dise\u00f1o innovador<\/strong> y <strong>Producci\u00f3n moderna de FBT<\/strong> reducirse significativamente.<\/p>\n<p>La culata trasera puede alinearse opcionalmente y las placas laterales de la culata central pueden personalizarse.<\/p>\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1706961575 > .col-inner {\n  margin: 0px 0px -30px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-1660511631\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1578976296\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1578976296 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_147310905\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img decoding=\"async\" width=\"300\" height=\"134\" src=\"https:\/\/ddoptics.shop\/wp-content\/uploads\/2021\/03\/black-fbt-logo-1.png\" class=\"attachment-large size-large\" alt=\"Logotipo FBT Fine Ballistic Tools\" srcset=\"https:\/\/ddoptics.shop\/wp-content\/uploads\/2021\/03\/black-fbt-logo-1.png 300w, https:\/\/ddoptics.shop\/wp-content\/uploads\/2021\/03\/black-fbt-logo-1-250x112.png 250w\" sizes=\"(max-width: 300px) 100vw, 300px\" title=\"\">\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_147310905 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f13334-o1\" lang=\"de-DE\" dir=\"ltr\" data-wpcf7-id=\"13334\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/es\/wp-json\/wp\/v2\/product\/26453#wpcf7-f13334-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Formulario de contacto\" novalidate=\"novalidate\" data-status=\"init\" data-trp-original-action=\"\/es\/wp-json\/wp\/v2\/product\/26453#wpcf7-f13334-o1\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"13334\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.5\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"de_DE\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f13334-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/><input type=\"hidden\" name=\"_wpcf7dtx_version\" value=\"5.0.5\" \/>\n<\/fieldset>\n<hr \/>\n<p><span style=\"font-size: large; color: #c4713a;\">\u00bfTiene alguna petici\u00f3n especial? Preguntar a Moritz de FBT es quiz\u00e1s siempre mejor?<\/span>\n<\/p>\n<p><span class=\"wpcf7-form-control-wrap\" data-name=\"name04\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Nombre y apellidos\" value=\"\" type=\"text\" name=\"name04\" \/><\/span>\n<\/p>\n<p><span class=\"wpcf7-form-control-wrap\" data-name=\"email04\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Direcci\u00f3n de correo electr\u00f3nico\" value=\"\" type=\"email\" name=\"email04\" \/><\/span>\n<\/p>\n<p><span class=\"wpcf7-form-control-wrap\" data-name=\"telefon04\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text\" aria-invalid=\"false\" placeholder=\"Indicativo interurbano N\u00famero de tel\u00e9fono\" value=\"\" type=\"text\" name=\"telefon04\" \/><\/span>\n<\/p>\n<p><span class=\"wpcf7-form-control-wrap\" data-name=\"homepage04\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text\" aria-invalid=\"false\" placeholder=\"P\u00e1gina de inicio opcional\" value=\"\" type=\"text\" name=\"homepage04\" \/><\/span>\n<\/p>\n<p><span class=\"wpcf7-form-control-wrap\" data-name=\"nachricht04\"><textarea cols=\"42\" rows=\"6\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Espacio para su mensaje\" name=\"nachricht04\"><\/textarea><\/span>\n<\/p>\n<p><div class=\"cf7-cf-turnstile\" style=\"margin-top: 0px; margin-bottom: -15px;\"> <div id=\"cf-turnstile-cf7-3921906067\" class=\"cf-turnstile\" data-sitekey=\"0x4AAAAAAABF73A72cG0R_Z9\" data-theme=\"auto\" data-language=\"auto\" data-size=\"normal\" data-retry=\"auto\" data-retry-interval=\"1000\" data-refresh-expired=\"auto\" data-refresh-timeout=\"auto\" data-action=\"contact-form-7\" data-callback=\"turnstileCF7Callback\" data-appearance=\"always\"><\/div> <script>document.addEventListener(\"DOMContentLoaded\", function() { setTimeout(function(){ var e=document.getElementById(\"cf-turnstile-cf7-3921906067\"); if(e&&!e.innerHTML.trim()){turnstile.render(e, {sitekey:\"0x4AAAAAAABF73A72cG0R_Z9\"});} }, 200); });<\/script> <br class=\"cf-turnstile-br cf-turnstile-br-cf7-3921906067\"> <style>#cf-turnstile-cf7-3921906067 { margin-left: -15px; }<\/style> <script>document.addEventListener(\"DOMContentLoaded\",function(){document.querySelectorAll('.wpcf7-form').forEach(function(e){e.addEventListener('submit',function(){if(document.getElementById('cf-turnstile-cf7-3921906067')){setTimeout(function(){turnstile.reset('#cf-turnstile-cf7-3921906067');},1000)}})})});<\/script> <\/div>\n<\/p>\n<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner\" type=\"submit\" value=\"Env\u00edo de\" \/>\n<\/p><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<input type=\"hidden\" name=\"trp-form-language\" value=\"es\"\/><\/form>\n<\/div>\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-481790564\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<blockquote><p>La reducci\u00f3n de peso y la mejora de las propiedades mec\u00e1nicas son las principales ventajas de la construcci\u00f3n ligera con compuestos de carbono.<\/p><\/blockquote>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n<div class=\"video video-fit mb\" style=\"padding-top:56.25%;\"><p><iframe title=\"culatas de carbono para todos los sistemas de rifle - Fine Ballistic Tools\" width=\"1020\" height=\"574\" src=\"https:\/\/www.youtube.com\/embed\/OODTsUzxZhc?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<\/div>\n<div class=\"text-center\"><div class=\"is-divider divider clearfix\" style=\"margin-top:2.0em;margin-bottom:2.0em;max-width:50%;\"><\/div><\/div>\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_53022558\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_53022558 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n<h3>La innovaci\u00f3n de FBT UNIC - construcci\u00f3n h\u00edbrida de pl\u00e1stico impreso en 3D con refuerzo de fibra de carbono + <a href=\"https:\/\/www.cerakote.com\/europe\" target=\"_blank\" rel=\"noopener sponsored\">Cerakote<\/a> Revestimiento<\/h3>\n<div class=\"row\"  id=\"row-915348186\">\n\n\t<div id=\"col-1788974648\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\" style=\"background-color:rgb(34, 34, 34);\" >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1537465277\">\n\t\t<a class=\"image-lightbox lightbox-gallery\" title=\"\" href=\"https:\/\/ddoptics.shop\/wp-content\/uploads\/2021\/03\/UNIC-Schaft-Detail-Lochgriff.jpg\">\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img decoding=\"async\" width=\"500\" height=\"334\" src=\"https:\/\/ddoptics.shop\/wp-content\/uploads\/2021\/03\/UNIC-Schaft-Detail-Lochgriff.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/ddoptics.shop\/wp-content\/uploads\/2021\/03\/UNIC-Schaft-Detail-Lochgriff.jpg 500w, https:\/\/ddoptics.shop\/wp-content\/uploads\/2021\/03\/UNIC-Schaft-Detail-Lochgriff-304x203.jpg 304w, https:\/\/ddoptics.shop\/wp-content\/uploads\/2021\/03\/UNIC-Schaft-Detail-Lochgriff-305x204.jpg 305w, https:\/\/ddoptics.shop\/wp-content\/uploads\/2021\/03\/UNIC-Schaft-Detail-Lochgriff-422x282.jpg 422w, https:\/\/ddoptics.shop\/wp-content\/uploads\/2021\/03\/UNIC-Schaft-Detail-Lochgriff-250x167.jpg 250w\" sizes=\"(max-width: 500px) 100vw, 500px\" title=\"\">\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"caption\">Culata FBT UNIC detalle agujero empu\u00f1adura<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/a>\t\t\n<style>\n#image_1537465277 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-838104793\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<ul>\n<li>Por lo tanto, la parte delantera y la culata son siempre la misma pieza.<\/li>\n<li>La secci\u00f3n central impresa en 3D siempre es diferente<br \/>\nEn <strong>Revestimiento Cerakote serie H<\/strong> es permanentemente resistente a la corrosi\u00f3n y ofrece una dureza y adherencia inigualables<\/li>\n<li><strong>Halder<\/strong> Tomas para \"<strong><a href=\"https:\/\/push-and-go.eu\/\" target=\"_blank\" rel=\"nofollow noopener sponsored\" data-schema-attribute=\"\">Empujar y seguir<\/a>\" Eslinga giratoria<\/strong> (integrado de serie)<\/li>\n<li><strong>B\u00edpode Spartan <\/strong><a href=\"https:\/\/javelinbipod.com\/collections\/adapters\/products\/gunsmith-adapters\" target=\"_blank\" rel=\"nofollow noopener sponsored\" data-schema-attribute=\"\"><strong>Toma de adaptador<\/strong><\/a> (integrado de serie)<\/li>\n<li>La secci\u00f3n central siempre es diferente<\/li>\n<li><strong>Peque\u00f1as series de modelos de armas<\/strong> en la calidad FBT habitual<\/li>\n<li>Ventaja de reducir los costes de fabricaci\u00f3n como beneficio para el cliente<\/li>\n<\/ul>\n<div class=\"row\"  id=\"row-635151967\">\n\n\t<div id=\"col-1688736933\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner text-left dark\"  >\n\t\t\t\n\t\t\t\n<ul>\n<li>Culata UNIC de arma larga para TODOS - rifles de cerrojo, rifles break-action, escopetas, etc.<\/li>\n<li>El eje perforado garantiza una ergonom\u00eda perfecta tanto para diestros como para zurdos.<\/li>\n<\/ul>\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1688736933 > .col-inner {\n  margin: 0px 0px -30px 0px;\n  border-radius: 10px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n<style>\n#row-635151967 > .col > .col-inner {\n  padding: 15px 0px 1px 0px;\n  background-color: #53a600;\n  border-radius: 10px;\n}\n<\/style>\n<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n<div class=\"text-center\"><div class=\"is-divider divider clearfix\" style=\"margin-top:2.0em;margin-bottom:2.0em;max-width:50%;\"><\/div><\/div>\n<h2><span style=\"font-size: 90%;\">El equipo de FINE BALLISTIC TOOLS est\u00e1 formado por ingeniosos innovadores que tambi\u00e9n cambiar\u00e1n radicalmente su modelo de armas.<\/span><\/h2>\n<p>En el <strong><a href=\"https:\/\/fineballistictools.com\/\" target=\"_blank\" rel=\"noopener sponsored\" data-schema-attribute=\"\">Empresa austriaca FBT<\/a><\/strong> se ha fijado el objetivo de <strong>las mejores varillas de carbono, las m\u00e1s ligeras, estables y con menor rebote<\/strong> para casi todos los <strong>Sistemas de armas<\/strong> para construir. Convierten cada arma en un <strong>herramienta de precisi\u00f3n ultramoderna<\/strong> con una ergonom\u00eda excepcional y el m\u00e1ximo ahorro de peso.<\/p>\n<blockquote><p>El precio de las varillas de carbono de alta calidad siempre ha sido muy elevado, ya que implican altos costes de fabricaci\u00f3n y s\u00f3lo son una alternativa a las varillas de pl\u00e1stico, normalmente baratas, si se tiene la cartera bien llena. FINE BALLISTIC TOOLS ha querido cambiar radicalmente esta situaci\u00f3n.<\/p><\/blockquote>\n<p>FBT significa<strong> Innovaci\u00f3n, calidad, durabilidad<\/strong> as\u00ed como intemporal y ergon\u00f3mico <strong>Dise\u00f1o,<\/strong> que satisface las necesidades actuales de <strong>Cazadores y tiradores<\/strong> y busca soluciones pr\u00e1cticas.<\/p>\n\t<div id=\"gap-1642930221\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-1642930221 {\n  padding-top: 20px;\n}\n<\/style>\n\t<\/div>\n\t\n\n\t<section class=\"section info-card-1 has-mask mask-angled\" id=\"section_1338724639\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t<div class=\"effect-sliding-glass bg-effect fill no-click\"><\/div>\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\t<div id=\"gap-541842318\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-541842318 {\n  padding-top: 30px;\n}\n<\/style>\n\t<\/div>\n\t\n<div class=\"row row-small align-equal\"  id=\"row-395767294\">\n\n\t<div id=\"col-1080310075\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"box has-hover   has-hover box-push box-text-bottom\" >\n\n\t\t<div class=\"box-image\" style=\"border-radius:5%;\">\n\t\t\t<a href=\"#\" >\t\t\t<div class=\"image-zoom image-cover\" style=\"padding-top:100%;\">\n\t\t\t\t<img decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/ddoptics.shop\/wp-content\/uploads\/2021\/03\/UNIC-Schaefte-Waffe.jpg\" class=\"attachment- size-\" alt=\"Culata de fibra de carbono UNIC para armas largas de FBT\" srcset=\"https:\/\/ddoptics.shop\/wp-content\/uploads\/2021\/03\/UNIC-Schaefte-Waffe.jpg 500w, https:\/\/ddoptics.shop\/wp-content\/uploads\/2021\/03\/UNIC-Schaefte-Waffe-304x304.jpg 304w, https:\/\/ddoptics.shop\/wp-content\/uploads\/2021\/03\/UNIC-Schaefte-Waffe-305x305.jpg 305w, https:\/\/ddoptics.shop\/wp-content\/uploads\/2021\/03\/UNIC-Schaefte-Waffe-340x340.jpg 340w, https:\/\/ddoptics.shop\/wp-content\/uploads\/2021\/03\/UNIC-Schaefte-Waffe-422x422.jpg 422w, https:\/\/ddoptics.shop\/wp-content\/uploads\/2021\/03\/UNIC-Schaefte-Waffe-250x250.jpg 250w\" sizes=\"(max-width: 500px) 100vw, 500px\" title=\"\">\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/a>\t\t<\/div>\n\n\t\t<div class=\"box-text text-center\" style=\"background-color:rgb(255, 255, 255);padding:20px 5px 19px 5px;\">\n\t\t\t<div class=\"box-text-inner\">\n\t\t\t\t\n<h3>El eje ultraligero UNIC<\/h3>\n<p>Reduce el peso total en unos 650 g. El eje UNIC es un h\u00edbrido de pl\u00e1stico impreso en 3D con refuerzo de fibra de carbono y piezas fabricadas en autoclave.<\/p>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1080310075 > .col-inner {\n  border-radius: 10px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-2100584289\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"box has-hover   has-hover box-push box-text-bottom\" >\n\n\t\t<div class=\"box-image\" style=\"border-radius:5%;\">\n\t\t\t<a href=\"#\" >\t\t\t<div class=\"image-zoom image-cover\" style=\"padding-top:100%;\">\n\t\t\t\t<img decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/ddoptics.shop\/wp-content\/uploads\/2021\/03\/UNIC-Backe-Verstellbar.jpg\" class=\"attachment- size-\" alt=\"Carrillera ajustable con eje de carbono UNIC\" srcset=\"https:\/\/ddoptics.shop\/wp-content\/uploads\/2021\/03\/UNIC-Backe-Verstellbar.jpg 500w, https:\/\/ddoptics.shop\/wp-content\/uploads\/2021\/03\/UNIC-Backe-Verstellbar-304x304.jpg 304w, https:\/\/ddoptics.shop\/wp-content\/uploads\/2021\/03\/UNIC-Backe-Verstellbar-305x305.jpg 305w, https:\/\/ddoptics.shop\/wp-content\/uploads\/2021\/03\/UNIC-Backe-Verstellbar-340x340.jpg 340w, https:\/\/ddoptics.shop\/wp-content\/uploads\/2021\/03\/UNIC-Backe-Verstellbar-422x422.jpg 422w, https:\/\/ddoptics.shop\/wp-content\/uploads\/2021\/03\/UNIC-Backe-Verstellbar-250x250.jpg 250w\" sizes=\"(max-width: 500px) 100vw, 500px\" title=\"\">\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/a>\t\t<\/div>\n\n\t\t<div class=\"box-text text-center\" style=\"background-color:rgb(255, 255, 255);padding:20px 5% 20px 5%;\">\n\t\t\t<div class=\"box-text-inner\">\n\t\t\t\t\n<h3>Eje est\u00e1ndar y personalizado<\/h3>\n<p>Las culatas delantera y trasera son siempre las mismas, la culata central o las piezas de uni\u00f3n para los sistemas de culata dividida se imprimen en 3D.<\/p>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-2100584289 > .col-inner {\n  border-radius: 10px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-886323066\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"box has-hover   has-hover box-push box-text-bottom\" >\n\n\t\t<div class=\"box-image\" style=\"border-radius:5%;\">\n\t\t\t<a href=\"#\" >\t\t\t<div class=\"image-zoom image-cover\" style=\"padding-top:100%;\">\n\t\t\t\t<img decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/ddoptics.shop\/wp-content\/uploads\/2021\/03\/UNIC-Standard-Carbon.jpg\" class=\"attachment- size-\" alt=\"Culata UNIC de Fine Balistic Tools\" srcset=\"https:\/\/ddoptics.shop\/wp-content\/uploads\/2021\/03\/UNIC-Standard-Carbon.jpg 500w, https:\/\/ddoptics.shop\/wp-content\/uploads\/2021\/03\/UNIC-Standard-Carbon-304x304.jpg 304w, https:\/\/ddoptics.shop\/wp-content\/uploads\/2021\/03\/UNIC-Standard-Carbon-305x305.jpg 305w, https:\/\/ddoptics.shop\/wp-content\/uploads\/2021\/03\/UNIC-Standard-Carbon-340x340.jpg 340w, https:\/\/ddoptics.shop\/wp-content\/uploads\/2021\/03\/UNIC-Standard-Carbon-422x422.jpg 422w, https:\/\/ddoptics.shop\/wp-content\/uploads\/2021\/03\/UNIC-Standard-Carbon-250x250.jpg 250w\" sizes=\"(max-width: 500px) 100vw, 500px\" title=\"\">\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/a>\t\t<\/div>\n\n\t\t<div class=\"box-text text-center\" style=\"background-color:rgb(255, 255, 255);padding:20px 5% 20px 5%;\">\n\t\t\t<div class=\"box-text-inner\">\n\t\t\t\t\n<h3>Eje de carbono No Limits<\/h3>\n<p>Ya sea rifle de repetici\u00f3n, rifle de ca\u00f1\u00f3n quebrado, viejo o nuevo. Como <strong>Eje con orificio de revoluci\u00f3n<\/strong> ofrece tanto para <strong>Diestro y zurdo<\/strong> ergonom\u00eda perfecta.<\/p>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-886323066 > .col-inner {\n  border-radius: 10px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n<style>\n#row-395767294 > .col > .col-inner {\n  background-color: rgb(255,255,255);\n}\n<\/style>\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1338724639 {\n  padding-top: 15px;\n  padding-bottom: 15px;\n  background-color: rgb(224, 224, 224);\n}\n<\/style>\n\t<\/section>\n\t\n\t<div id=\"gap-9643119\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-9643119 {\n  padding-top: 29px;\n}\n<\/style>\n\t<\/div>\n\t\n<h3 style=\"text-align: center;\"><span style=\"font-size: 200%;\"><span style=\"font-size: 300%;\">FBT Y CARBONO\u00a0<\/span><br \/>\n<\/span><span style=\"font-size: 150%;\">... un poco de historia con informaci\u00f3n de fondo.<\/span><\/h3>\n<p style=\"text-align: center;\">Desde la primera <strong>Modelo FBT Carbon<\/strong> para el sistema Blaser R8, la familia de modelos de stock ha crecido considerablemente. <strong>Tikka, Sauer, Mauser, Steyr, HEYM y HOWA<\/strong> se sirven con las culatas monocasco. Ahora FBT tambi\u00e9n puede afirmar que es capaz de equipar cualquier sistema de armas con una culata de carbono. El nombre de la nueva culata milagrosa: UNIC Universal Carbon Stock.<\/p>\n<section class=\"av_textblock_section\">\n<div class=\"avia_textblock\">\n<h2 id=\"se\" style=\"text-align: center;\">CULATA SUPERERGON\u00d3MICA<\/h2>\n<\/div>\n<\/section>\n<section class=\"av_textblock_section\">\n<div class=\"avia_textblock thinP\">\n<p>Como la culata thumbhole no s\u00f3lo tiene ventajas para los rifles de cerrojo con cerrojos de cilindro giratorio, FBT ha desarrollado la llamada culata \"Superergon\u00f3mica\". Ofrece la misma posici\u00f3n relajada de empu\u00f1adura de pistola que la culata thumbhole, pero permite una acci\u00f3n de repetici\u00f3n superr\u00e1pida.<\/p>\n<section class=\"av_textblock_section\">\n<div class=\"avia_textblock\">\n<h2 id=\"rv\" style=\"text-align: center;\">ARMAMENTO DE LA REVOLUCI\u00d3N<\/h2>\n<\/div>\n<\/section>\n<div class=\"hr hr-custom hr-center hr-icon-no avia-builder-el-24 el_after_av_textblock el_before_av_textblock\"><span style=\"color: #555555;\">Probado mil veces y sigue siendo el cl\u00e1sico. El <strong>Forma de eje trasero recto<\/strong> gestiona el <strong>Retroceso directo y recto al hombro<\/strong> del tirador y evita el desagradable golpe ascendente del rifle.<\/span><\/div>\n<div class=\"hr hr-custom hr-center hr-icon-no avia-builder-el-24 el_after_av_textblock el_before_av_textblock\"><span style=\"color: #555555;\"> A pesar de la<strong> bajo peso<\/strong> el retroceso incluso con calibres potentes como 300 Winchester Magnum o incluso<a href=\"https:\/\/de.wikipedia.org\/wiki\/.338_Lapua_Magnum\" target=\"_blank\" rel=\"noopener sponsored\" data-schema-attribute=\"\"> 338 Lapua Magnum<\/a> puede seguir describi\u00e9ndose como confortable. Disponible como eje monocasco o como eje de carbono universal UNIC.<\/span><\/div>\n<\/div>\n<\/section>\n<div class=\"hr hr-invisible avia-builder-el-19 el_after_av_textblock el_before_av_image\"><\/div>\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_2104488367\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_2104488367 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n<div class=\"text-center\"><div class=\"is-divider divider clearfix\" style=\"margin-top:2.0em;margin-bottom:2.0em;max-width:50%;\"><\/div><\/div>\n\n\t<section class=\"section\" id=\"section_183763192\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row align-center\"  id=\"row-657525056\">\n\n\t<div id=\"col-1168088274\" class=\"col medium-5 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner text-left\"  >\n\t\t\t\n\t\t\t\n<h3><span style=\"font-size: 300%; color: #f4bf1e;\"><span style=\"color: #c4713a;\">La fascinaci\u00f3n de los ejes de carbono<\/span><br \/>\n<\/span><\/h3>\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1168088274 > .col-inner {\n  padding: 0px 0px 0px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-1559997719\" class=\"col medium-7 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner text-left\"  >\n\t\t\t\n\t\t\t\n<p class=\"lead\">La Culata de Carbono Universal UNIC puede adaptarse a cualquier sistema de armas. Si a\u00fan no dispone del sistema correspondiente en su gama, FBT simplemente escanear\u00e1 su rifle y personalizar\u00e1 la culata.<\/p>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n<div class=\"row\"  id=\"row-400549214\">\n\n\t<div id=\"col-996585158\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n<p><span style=\"font-size: 150%;\">Peso de las existencias FBT UNIC<\/span><\/p>\n<p>\u00bfC\u00f3mo de ligero es el eje de carbono? Definimos en 10 niveles de 0 (pesado) a 10 (superligero).<\/p>\n<p><span style=\"color: #c4713a; font-size: 500%;\"><span class=\"count-up\">10<\/span>\/10<\/span><\/p>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-10028541\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n<p><span style=\"font-size: 150%;\">Conjunto del eje UNIC<\/span><\/p>\n<p>\u00bfC\u00f3mo de dif\u00edcil es el autoensamblaje? Lo definimos en 10 niveles de 0 (dif\u00edcil) a 10 (muy f\u00e1cil)<\/p>\n<p><span style=\"color: #c4713a; font-size: 500%;\"><span class=\"count-up\">9<\/span>\/10<\/span><\/p>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-292801894\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n<p><span style=\"font-size: 150%;\">UNIC y Winchester SXR2 Ergonom\u00eda<\/span><\/p>\n<p>\u00bfQu\u00e9 se siente al disparar el arma tuneada UNIC? Definimos el factor de diversi\u00f3n de 1 (m\u00e1s bien soso) a 10 (superguay).<\/p>\n<p><span style=\"color: #c4713a; font-size: 500%;\"><span class=\"count-up\">10<\/span>\/10<\/span><\/p>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_183763192 {\n  padding-top: 0px;\n  padding-bottom: 0px;\n}\n<\/style>\n\t<\/section>\n\t\n<div class=\"text-center\"><div class=\"is-divider divider clearfix\" style=\"margin-top:2.0em;margin-bottom:2.0em;max-width:50%;\"><\/div><\/div>\n\n\t<section class=\"section dark has-parallax\" id=\"section_2086123660\">\n\t\t<div class=\"section-bg fill\" data-parallax-container=\".section\" data-parallax-background data-parallax=\"-3\">\n\t\t\t\t\t\t\t\t\t<div class=\"section-bg-overlay absolute fill\"><\/div>\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row\"  id=\"row-1442371871\">\n\n\t<div id=\"col-1681494679\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<h3>Por qu\u00e9 el carbono<\/h3>\n<div class=\"accordion\">\n\t<div id=\"accordion-2815427733\" class=\"accordion-item\">\n\t\t<a id=\"accordion-2815427733-label\" class=\"accordion-title plain active\" href=\"#accordion-item-eigenschaften-von-carbon\" aria-expanded=\"true\" aria-controls=\"accordion-2815427733-content\">\n\t\t\t<button class=\"toggle\" aria-label=\"Toggle\"><i class=\"icon-angle-down\" aria-hidden=\"true\"><\/i><\/button>\n\t\t\t<span>Propiedades del carbono<\/span>\n\t\t<\/a>\n\t\t<div id=\"accordion-2815427733-content\" class=\"accordion-inner\" style=\"display: block;\" aria-labelledby=\"accordion-2815427733-label\">\n\t\t\t\n<h3>\u00bfQu\u00e9 califica al carbono como material para las culatas de las armas modernas?<\/h3>\n<p><strong>El carbono es un material moderno y extremadamente pr\u00e1ctico.<\/strong> El carbono es un <strong>Muy ligero, estable y resistente a la corrosi\u00f3n<\/strong> Un material que desde hace mucho tiempo es est\u00e1ndar en muchos \u00e1mbitos de la tecnolog\u00eda pesada. El\u00a0<b>Fuerza<\/b> supera a la de la mayor\u00eda de los metales y otros materiales compuestos de fibra. \u00c9sta es probablemente una de las razones por las que la fibra de carbono es tambi\u00e9n uno de los <a href=\"https:\/\/ddoptics.shop\/es\/video-prueba-de-sonido-del-silenciador-inca\/\" target=\"_blank\" rel=\"noopener\" data-schema-attribute=\"\">Silenciadores FBT<\/a> se utiliza.<\/p>\n<p>Cuando el <strong>Construcci\u00f3n del mango<\/strong> es correcto, entonces a <strong>Culata de fibra de carbono mucho m\u00e1s agradable en el comportamiento de retroceso<\/strong> que un enchufe comparable de <strong>Aluminio, fibra de vidrio o madera.<\/strong> Los ciclistas profesionales, por ejemplo, tambi\u00e9n lo notan: el cuadro de carbono es mucho m\u00e1s c\u00f3modo de conducir.<\/p>\n<div>\n<p class=\"\">Las ventajas para las reservas de armas tambi\u00e9n son evidentes en este caso:<\/p>\n<ul>\n<li>Peso reducido<\/li>\n<li>Amortiguador<\/li>\n<li>Resistente a todas las condiciones meteorol\u00f3gicas<\/li>\n<li>Extremadamente estable<\/li>\n<li>F\u00e1cil de limpiar<\/li>\n<\/ul>\n<blockquote><p>Por ello, el material de carbono es especialmente adecuado para la caza activa o intensiva, donde la fiabilidad, la robustez y el peso son importantes.<\/p><\/blockquote>\n<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\n\t<div id=\"accordion-4034450720\" class=\"accordion-item\">\n\t\t<a id=\"accordion-4034450720-label\" class=\"accordion-title plain\" href=\"#accordion-item-was-macht-einen-guten-carbonschaft-aus?\" aria-expanded=\"false\" aria-controls=\"accordion-4034450720-content\">\n\t\t\t<button class=\"toggle\" aria-label=\"Toggle\"><i class=\"icon-angle-down\" aria-hidden=\"true\"><\/i><\/button>\n\t\t\t<span>\u00bfC\u00f3mo debe ser un buen eje de fibra de carbono?<\/span>\n\t\t<\/a>\n\t\t<div id=\"accordion-4034450720-content\" class=\"accordion-inner\" aria-labelledby=\"accordion-4034450720-label\">\n\t\t\t\n<p>Especialmente estos\u00a0<b>propiedades amortiguadoras<\/b> hacen que este material sea muy interesante para la fabricaci\u00f3n de culatas de fusil.<\/p>\n<p>En el primer rodaje con un<strong> eje de carbono bien construido<\/strong> notar\u00e1 inmediatamente que el rifle ahora optimizado con culata de fibra de carbono UNIC es mucho m\u00e1s c\u00f3modo de disparar que antes.<\/p>\n<blockquote><p>Incluso las ca\u00f1as de madera se superan sin concesiones.<\/p><\/blockquote>\n<p>Especialmente el <strong>Construcci\u00f3n interna de la toma<\/strong> siempre tendr\u00e1 un <strong>influencia central en la amortiguaci\u00f3n de las vibraciones<\/strong> tener. Es importante que la mano de obra sea impecable y que la capa superior sea perfecta por el aspecto del carbono<\/p>\n<p>Todos los bordes deben ser lisos (una importante caracter\u00edstica de calidad) y el <strong>La superficie debe ser mate<\/strong> se mantienen en su sitio. Esto proporciona al eje un mejor agarre en condiciones h\u00famedas. <strong>mejor agarre.<\/strong><\/p>\n\t\t<\/div>\n\t<\/div>\n\t\n\t<div id=\"accordion-478060575\" class=\"accordion-item\">\n\t\t<a id=\"accordion-478060575-label\" class=\"accordion-title plain\" href=\"#accordion-item-fazit\" aria-expanded=\"false\" aria-controls=\"accordion-478060575-content\">\n\t\t\t<button class=\"toggle\" aria-label=\"Toggle\"><i class=\"icon-angle-down\" aria-hidden=\"true\"><\/i><\/button>\n\t\t\t<span>Conclusi\u00f3n<\/span>\n\t\t<\/a>\n\t\t<div id=\"accordion-478060575-content\" class=\"accordion-inner\" aria-labelledby=\"accordion-478060575-label\">\n\t\t\t\n<p>Los ejes de carbono son m\u00e1s caros, pero est\u00e1n muy de moda debido a las ventajas mencionadas anteriormente.<\/p>\n<p>En<strong> Eje FBT UNIC<\/strong> tiene un<strong> Dise\u00f1o sofisticado<\/strong> y se fabrica con m\u00e9todos de producci\u00f3n modernos. El resultado son unos costes de fabricaci\u00f3n favorables y, en consecuencia, un precio de venta muy interesante.<\/p>\n<p>Si nos fijamos en los productos de la competencia, este precio puede calificarse de muy asequible para los cazadores. Una cosa no debe ser olvidada: Usted obtiene un <strong>producto de primera calidad, en parte hecho a mano,<\/strong> con el que experimentar\u00e1s muchas cosas y disfrutar\u00e1s de \u00e9l durante mucho tiempo.<\/p>\n\t\t<\/div>\n\t<\/div>\n\t\n<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_2086123660 {\n  padding-top: 20px;\n  padding-bottom: 20px;\n}\n#section_2086123660 .section-bg-overlay {\n  background-color: rgba(0, 0, 0, 0.7);\n}\n<\/style>\n\t<\/section>","protected":false},"excerpt":{"rendered":"<p><img decoding=\"async\" class=\"alignright wp-image-23904\" src=\"https:\/\/ddoptics.shop\/wp-content\/uploads\/2021\/03\/Austria2.svg\" alt=\"Fabricado en Austria\" width=\"150\" height=\"150\" \/>\u00a1Experimente HOY los ejes de carbono de MA\u00d1ANA!<\/p>\n<p>... o dicho de otro modo: <strong>M\u00c1S<\/strong>\u00a0Ergonom\u00eda,\u00a0<strong>M\u00c1S<\/strong>\u00a0Precisi\u00f3n,\u00a0<strong>MENOS<\/strong> \u00a1Peso con su arma de fuego est\u00e1ndar Winchester SXR2!<br \/>\n<a href=\"https:\/\/ddoptics.shop\/es\/eje-fbt-unic-carbono-eje-perforado\/\" target=\"_blank\" class=\"button primary is-primary is-small\" rel=\"noopener\" >\n\t\t<span>Desarrollo de la entrevista FBT<\/span>\n\t<\/a>\n\n<div class=\"is-divider divider clearfix\" style=\"max-width:small;\"><\/div>\r\n<ul>\r\n \t<li><span style=\"font-size: 90%;\"><span style=\"color: #ed1c24;\">Nuestra<strong><a href=\"https:\/\/ddoptics.shop\/es\/clientes-suiza-liechtenstein\/\" target=\"_blank\" rel=\"noopener\"> Autorizaciones globales<\/a> <\/strong>para exportaci\u00f3n | ver pa\u00edses<\/span><\/span><\/li>\r\n \t<li><span style=\"font-size: 90%;\"><span style=\"color: #ed1c24;\">Factura Klarna<\/span> debido a la <strong>Tiempo de fabricaci\u00f3n aprox. 10-12 semanas<\/strong> \u00a1imposible!<\/span><\/li>\r\n \t<li><span style=\"font-size: 90%;\"><strong>Formas de pago:<\/strong> Prepago \u20ac1.000,-- dep\u00f3sito en garant\u00eda o 100% proveedor de pago.<\/span><\/li>\r\n<\/ul>","protected":false},"featured_media":26461,"comment_status":"open","ping_status":"closed","template":"","meta":{"inline_featured_image":false,"footnotes":""},"product_brand":[],"product_cat":[1127],"product_tag":[985,986,984,1126],"class_list":{"0":"post-26453","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-winchester-waffen","7":"product_tag-carbon-schaft","8":"product_tag-fbt","9":"product_tag-unic-schaft","10":"product_tag-winchester-sxr2","11":"product_shipping_class-paket","12":"pa_brand-marke-fbt-fine-ballistic-tools","13":"pa_farbe-schwarz","14":"pa_produkt-typ-carbon-wechselschaft-langwaffen","16":"first","17":"instock","18":"taxable","19":"shipping-taxable","20":"purchasable","21":"product-type-bundle"},"bundled_by":[],"bundle_stock_status":"instock","bundle_stock_quantity":"","bundle_virtual":false,"bundle_layout":"default","bundle_add_to_cart_form_location":"default","bundle_editable_in_cart":false,"bundle_sold_individually_context":"product","bundle_item_grouping":"parent","bundle_min_size":"","bundle_max_size":"","bundle_price":{"price":{"min":{"incl_tax":"1790","excl_tax":"1491.67"},"max":{"incl_tax":"2718","excl_tax":"2265"}},"regular_price":{"min":{"incl_tax":"1790","excl_tax":"1491.67"},"max":{"incl_tax":"2760","excl_tax":"2300"}}},"bundled_items":[{"bundled_item_id":360,"product_id":24862,"menu_order":0,"quantity_min":1,"quantity_max":1,"quantity_default":1,"priced_individually":false,"shipped_individually":false,"override_title":true,"title":"","override_description":false,"description":"","optional":false,"hide_thumbnail":true,"discount":"","override_variations":false,"allowed_variations":[24867,24866],"override_default_variation_attributes":false,"default_variation_attributes":[{"id":45,"name":"Versi\u00f3n de culata de rifle","option":"rechtsschaft"}],"single_product_visibility":"visible","cart_visibility":"visible","order_visibility":"visible","single_product_price_visibility":"visible","cart_price_visibility":"visible","order_price_visibility":"visible","stock_status":"in_stock"},{"bundled_item_id":391,"product_id":27091,"menu_order":1,"quantity_min":1,"quantity_max":1,"quantity_default":1,"priced_individually":true,"shipped_individually":false,"override_title":false,"title":"Acabado superficial UNIC","override_description":false,"description":"","optional":false,"hide_thumbnail":false,"discount":"","override_variations":false,"allowed_variations":[],"override_default_variation_attributes":false,"default_variation_attributes":[],"single_product_visibility":"visible","cart_visibility":"visible","order_visibility":"visible","single_product_price_visibility":"visible","cart_price_visibility":"visible","order_price_visibility":"visible","stock_status":"in_stock"},{"bundled_item_id":361,"product_id":23845,"menu_order":2,"quantity_min":1,"quantity_max":1,"quantity_default":1,"priced_individually":true,"shipped_individually":false,"override_title":true,"title":"","override_description":false,"description":"","optional":false,"hide_thumbnail":false,"discount":"","override_variations":false,"allowed_variations":[23847,23848,23849],"override_default_variation_attributes":true,"default_variation_attributes":[{"id":40,"name":"Longitud deseada del eje","option":"standard-36-5-cm"}],"single_product_visibility":"visible","cart_visibility":"visible","order_visibility":"visible","single_product_price_visibility":"visible","cart_price_visibility":"visible","order_price_visibility":"visible","stock_status":"in_stock"},{"bundled_item_id":362,"product_id":23853,"menu_order":3,"quantity_min":1,"quantity_max":1,"quantity_default":1,"priced_individually":true,"shipped_individually":false,"override_title":true,"title":"","override_description":true,"description":"","optional":false,"hide_thumbnail":false,"discount":"","override_variations":false,"allowed_variations":[],"override_default_variation_attributes":false,"default_variation_attributes":[{"id":41,"name":"Placa lateral","option":"cfk-platte"}],"single_product_visibility":"visible","cart_visibility":"visible","order_visibility":"visible","single_product_price_visibility":"visible","cart_price_visibility":"visible","order_price_visibility":"visible","stock_status":"in_stock"},{"bundled_item_id":363,"product_id":23851,"menu_order":4,"quantity_min":1,"quantity_max":1,"quantity_default":1,"priced_individually":true,"shipped_individually":false,"override_title":true,"title":"","override_description":true,"description":"Se puede reequipar","optional":false,"hide_thumbnail":false,"discount":"","override_variations":false,"allowed_variations":[],"override_default_variation_attributes":false,"default_variation_attributes":[],"single_product_visibility":"visible","cart_visibility":"visible","order_visibility":"visible","single_product_price_visibility":"visible","cart_price_visibility":"visible","order_price_visibility":"visible","stock_status":"in_stock"},{"bundled_item_id":364,"product_id":25506,"menu_order":5,"quantity_min":1,"quantity_max":1,"quantity_default":1,"priced_individually":true,"shipped_individually":false,"override_title":true,"title":"Haga su pedido: Halder eslinga giratoria","override_description":false,"description":"","optional":true,"hide_thumbnail":false,"discount":"","override_variations":false,"allowed_variations":[],"override_default_variation_attributes":false,"default_variation_attributes":[],"single_product_visibility":"visible","cart_visibility":"visible","order_visibility":"visible","single_product_price_visibility":"visible","cart_price_visibility":"visible","order_price_visibility":"visible","stock_status":"in_stock"},{"bundled_item_id":365,"product_id":24145,"menu_order":6,"quantity_min":1,"quantity_max":1,"quantity_default":1,"priced_individually":true,"shipped_individually":false,"override_title":true,"title":"Haga su pedido ahora: B\u00edpode Spartan Javelin Original","override_description":true,"description":"","optional":true,"hide_thumbnail":false,"discount":"10","override_variations":false,"allowed_variations":[],"override_default_variation_attributes":false,"default_variation_attributes":[],"single_product_visibility":"visible","cart_visibility":"visible","order_visibility":"visible","single_product_price_visibility":"visible","cart_price_visibility":"visible","order_price_visibility":"visible","stock_status":"in_stock"}],"bundle_sell_ids":[],"_links":{"self":[{"href":"https:\/\/ddoptics.shop\/es\/wp-json\/wp\/v2\/product\/26453","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ddoptics.shop\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/ddoptics.shop\/es\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/ddoptics.shop\/es\/wp-json\/wp\/v2\/comments?post=26453"}],"version-history":[{"count":11,"href":"https:\/\/ddoptics.shop\/es\/wp-json\/wp\/v2\/product\/26453\/revisions"}],"predecessor-version":[{"id":28155,"href":"https:\/\/ddoptics.shop\/es\/wp-json\/wp\/v2\/product\/26453\/revisions\/28155"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ddoptics.shop\/es\/wp-json\/wp\/v2\/media\/26461"}],"wp:attachment":[{"href":"https:\/\/ddoptics.shop\/es\/wp-json\/wp\/v2\/media?parent=26453"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/ddoptics.shop\/es\/wp-json\/wp\/v2\/product_brand?post=26453"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/ddoptics.shop\/es\/wp-json\/wp\/v2\/product_cat?post=26453"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/ddoptics.shop\/es\/wp-json\/wp\/v2\/product_tag?post=26453"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}