{"id":2588,"date":"2010-09-01T15:02:59","date_gmt":"2010-09-01T13:02:59","guid":{"rendered":"http:\/\/www.optik-sport-shop.at\/?p=2588"},"modified":"2026-04-14T10:05:23","modified_gmt":"2026-04-14T08:05:23","slug":"magazine-visier-09-2010","status":"publish","type":"post","link":"https:\/\/ddoptics.shop\/fr\/zeitschrift-visier-09-2010\/","title":{"rendered":"Magazine Visier num\u00e9ro 09\/2010"},"content":{"rendered":"<h2>Nighteagle 2,5-15\u00d750 est le nom du nouvel IF de DDoptics<\/h2>\n<p><span style=\"font-size: 13px;\">(rapport sous forme de <strong>pdf \u00e0 t\u00e9l\u00e9charger<\/strong>)<\/span><\/p>\n<p>Sur le site <a href=\"https:\/\/ddoptics.shop\/fr\/acheter\/lunette-de-visee-ddoptics-v6-2komma5-15x50-n-fx-mrad\/\"><span style=\"color: #0000ff;\"><strong><span style=\"color: #0000ff;\">DDoptics Nighteagle 2,5-15\u00d750<\/span><\/strong><\/span><\/a> est de <strong>Transmission de la lumi\u00e8re<\/strong>\u00a095\/93 pour cent (jour\/nuit).<\/p>\n<p>Selon l'usine, les jumelles peuvent remplir la fonction d'une petite longue-vue lors de la chasse de jour. Le site <strong>R\u00e9ticule lumineux 4<\/strong> se trouve dans le plan de l'image de l'oculaire (= 2e plan de l'image) et reste toujours de la m\u00eame taille lors du changement de grossissement. Il existe un <strong>point lumineux en fibre de verre \u00e0 intensit\u00e9 variable<\/strong> avec un circuit \u00e9lectronique r\u00e9vis\u00e9 et si petit qu'il ne doit masquer la cible que de mani\u00e8re minimale.<span style=\"text-align: center;\">\u00a0<\/span><\/p>\n<p>Le site <strong>L'unit\u00e9 d'\u00e9clairage est fabriqu\u00e9e \u00e0 la main<\/strong>Les souhaits des clients peuvent \u00eatre pris en compte.<\/p>\n<p>Le site <strong>L'optique est remplie d'azote<\/strong>, Elle est dot\u00e9e d'un tube en duralumin anodis\u00e9 d'une seule pi\u00e8ce.<\/p>\n<p>D\u00e9tails : <strong>extr\u00e9mit\u00e9 de l'oculaire caoutchout\u00e9e<\/strong> avec compensation de dioptrie (-3 \u00e0 +4), optique enti\u00e8rement trait\u00e9e, taux de lumi\u00e8re parasite minimal. R\u00e9glage du r\u00e9ticule sans outil : 0,25 MOA par clic (= de 7,3 mm\/100 m). Compensation de la parallaxe de 20 yards \u00e0 l'infini. <strong>Diam\u00e8tre de montage de l'anneau : 30mm.<\/strong><\/p>\n<p>Distance oculaire standard de 89 mm. Prix : 869 euros.<\/p>","protected":false},"excerpt":{"rendered":"<p>Communiqu\u00e9 de presse dans Visier 10\/2009. Nachtfalke 2,5-15 x 50 - Nouvelle lunette de vis\u00e9e pour la chasse et le sport<\/p>","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[176],"tags":[],"class_list":["post-2588","post","type-post","status-publish","format-standard","hentry","category-presseberichte"],"_links":{"self":[{"href":"https:\/\/ddoptics.shop\/fr\/wp-json\/wp\/v2\/posts\/2588","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ddoptics.shop\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ddoptics.shop\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ddoptics.shop\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/ddoptics.shop\/fr\/wp-json\/wp\/v2\/comments?post=2588"}],"version-history":[{"count":1,"href":"https:\/\/ddoptics.shop\/fr\/wp-json\/wp\/v2\/posts\/2588\/revisions"}],"predecessor-version":[{"id":25708,"href":"https:\/\/ddoptics.shop\/fr\/wp-json\/wp\/v2\/posts\/2588\/revisions\/25708"}],"wp:attachment":[{"href":"https:\/\/ddoptics.shop\/fr\/wp-json\/wp\/v2\/media?parent=2588"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ddoptics.shop\/fr\/wp-json\/wp\/v2\/categories?post=2588"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ddoptics.shop\/fr\/wp-json\/wp\/v2\/tags?post=2588"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}