{"id":6631,"date":"2014-07-24T15:40:16","date_gmt":"2014-07-24T13:40:16","guid":{"rendered":"http:\/\/optik-sport-shop.at\/?p=6631"},"modified":"2016-05-03T23:32:44","modified_gmt":"2016-05-03T21:32:44","slug":"chassetalk-chasse-et-public","status":"publish","type":"post","link":"https:\/\/ddoptics.shop\/fr\/jagdtalk-jagd-und-oeffentlichkeit\/","title":{"rendered":"Jagd und Natur TV Jagdtalk : Chasse et public - Le silence dans la for\u00eat ?"},"content":{"rendered":"<h2>TIPP - Enregistrement \u00e0 voir Chasse et nature TV : Chasse et public - Le silence dans la for\u00eat ?<\/h2>\n<p><img decoding=\"async\" class=\"alignleft wp-image-6559\" src=\"http:\/\/optik-sport-shop.at\/wp-content\/uploads\/2014\/07\/jagd-und-natur-tv.jpg\" alt=\"Chasse-et-nature-TV\" width=\"169\" height=\"41\" title=\"\"><a title=\"Vers la page Chasse et nature TV\" href=\"http:\/\/www.jagdundnatur.tv\" target=\"_blank\" rel=\"noopener\">Chasse et nature TV<\/a> est le premier <strong>cha\u00eene francophone pour les chasseurs, les p\u00eacheurs et les amoureux de la nature.<\/strong><\/p>\n<p><strong>Th\u00e8me de cette discussion sur la chasse :<\/strong> <strong>Les repr\u00e9sentants des int\u00e9r\u00eats de la chasse dans les pays germanophones communiquent-ils correctement ?<\/strong> Communiquent-ils seulement ? Quels sont les concepts permettant d'ancrer \u00e0 nouveau la chasse en tant que bien culturel mill\u00e9naire dans notre soci\u00e9t\u00e9 influenc\u00e9e par la mondialisation et vivant de mani\u00e8re de plus en plus urbaine et \u00e9trang\u00e8re \u00e0 la nature ? Est-il d\u00e9j\u00e0 trop tard ?<\/p>\n<p><strong>D\u00e9clarations personnelles des parties prenantes pr\u00e9sentes :<\/strong> Voir<strong> Besoin de changement<\/strong>... ; Les <strong>La chasse doit \u00eatre repositionn\u00e9e au niveau mondial<\/strong>Il y a plusieurs publics, mais une seule nature. <strong>La meilleure communication gagne l'int\u00e9r\u00eat de la majorit\u00e9<\/strong>La politique de la chasse se fait \u00e0 Bruxelles. Et personne n'y d\u00e9fend nos int\u00e9r\u00eats ; <strong>Les relations publiques professionnelles n'ont PAS lieu dans la chasse<\/strong>... ; En tant que chasseurs, nous nous laissons beaucoup trop traiter au lieu d'agir nous-m\u00eames ; Dans les <strong>Les associations de chasseurs rejettent le renouvellement comme un danger<\/strong> et donc une communication efficace est \u00e9galement vou\u00e9e \u00e0 l'\u00e9chec.<\/p>\n<h3>Contenu des discussions : <strong>Extrait du contenu de la vid\u00e9o avec temps de lecture<\/strong><\/h3>\n<ul>\n<li>Est-il possible de <strong>D\u00e9finir la marque chasse chez nous<\/strong> - 4:45<\/li>\n<li>La fauconnerie, en tant que petit groupe de chasse, a eu l'id\u00e9e de devenir un patrimoine culturel mondial - 6:14<\/li>\n<li>Il faut <strong>au go\u00fbt du jour<\/strong> dans les<strong> R\u00e9former les f\u00e9d\u00e9rations de chasse<\/strong> et <strong>tenir compte des \u00e9volutions<\/strong>. Nous avons par exemple des chasseuses, mais pas de fonctionnaire. Nous avons aussi une <strong>Vieillissement des fonctionnaires (fonction \u00e0 vie - est-ce repr\u00e9sentatif)<\/strong>\u00a0 - 7:30<\/li>\n<li>Nous avons un <strong>Gap entre les g\u00e9n\u00e9rations<\/strong>, <strong>ce que l'on entend par chasse<\/strong> - 8:50<\/li>\n<li>Nous ne faisons pas de relations publiques pour les chasseurs mais pour les non-chasseurs (Allemagne), cette compr\u00e9hension me manque en Autriche - 10:20<\/li>\n<li>Il y a <strong>Pas de strat\u00e9gie l\u00e0 o\u00f9 les probl\u00e8mes se posent<\/strong>M\u00e9dias \u00e9lectroniques, r\u00e9seaux sociaux(exemple : <strong>Comment se comporter en tant que chasseur sur Internet, quelles photos puis-je poster ?<\/strong>(comment \u00e9crire l'histoire sans froisser les non-chasseurs) - 11:25<\/li>\n<li>Ce qui me manque, c'est ce que les f\u00e9d\u00e9rations de chasseurs comptent faire en mati\u00e8re de strat\u00e9gie (le chasseur ne se sent pas repr\u00e9sent\u00e9, il se sent gouvern\u00e9) - 11:50<\/li>\n<li>Pourquoi la repr\u00e9sentation de la chasse aupr\u00e8s du public a-t-elle tant de mal ? - 12:45<\/li>\n<li><strong><a title=\"Portail des chasseurs du Vorarlberg\" href=\"http:\/\/www.vjagd.at\" target=\"_blank\" rel=\"noopener\">Les chasseurs du Vorarlberg n'ont pas d\u00e9velopp\u00e9 de site Internet, mais un Web2.0 www.vjagd.at<\/a> Portail avec communaut\u00e9 et mise en r\u00e9seau facebook.   - 15:20<\/strong><\/li>\n<li>Combien de temps la chasse peut-elle encore tra\u00eener les pieds, que se passera-t-il si rien ne change ? - 16:25<\/li>\n<li>Tous les utilisateurs de la nature se saluent quand ils se rencontrent dans la nature, \u00e0 la chasse tout doit \u00eatre calme - perturbateurs - 18:00<\/li>\n<li>Nous devons d\u00e9finir ce qu'est la chasse et pourquoi nous communiquons (message) - 26:45<\/li>\n<li><strong>La communication doit \u00eatre professionnelle<\/strong> \u00eatre fait - 28:50<\/li>\n<li>\u00c9galit\u00e9 dans la chasse, la chasse \u00e0 l'arc, la fauconnerie, etc. - 34:00<\/li>\n<li>Si je <strong>Si je mise trop sur ce qui a fait ses preuves, je risque de passer \u00e0 c\u00f4t\u00e9 de d\u00e9veloppements.<\/strong> et je cours apr\u00e8s et je dois assainir - 36:00<\/li>\n<li><strong>Qualification des fonctionnaires - le profil d'exigences a chang\u00e9.<\/strong> Quel est le degr\u00e9 de r\u00e9ussite de nos syst\u00e8mes de fonctionnaires ? 38:10<\/li>\n<li>Nous sommes confront\u00e9s \u00e0 un sujet tabou : Tuer - et nous vivons dans une soci\u00e9t\u00e9 o\u00f9 la mort est tr\u00e8s mal v\u00e9cue - 40:30<\/li>\n<li>Les chasseurs des vall\u00e9es ne s'int\u00e9ressent pas \u00e0 ce que fait la chasse en Namibie, etc., nos membres ont d'autres int\u00e9r\u00eats. Ces objectifs doivent \u00eatre pris en compte. - 41:50<\/li>\n<li>Nous ne sommes pas les seuls \u00e0 tuer, d'autres le font aussi, des p\u00eacheurs, etc. - 44:50<\/li>\n<li><strong>Il se passe beaucoup de choses positives dans la for\u00eat, mais le citadin n'en est pas inform\u00e9.<\/strong> Il est assis devant facebook et \u00e9crit sur quelque chose qu'il ne comprend pas ... - 45:30<\/li>\n<li>Se fier \u00e0 la politique et \u00e0 la d\u00e9mocratie : 90% des partisans de la chasse sont ambivalents - voteront contre la chasse en cas de doute. Un basculement peut \u00eatre rapide - 47:00<\/li>\n<li>Dans les m\u00e9dias, je vois les suspects habituels lors des repas de mai, des semaines du gibier, etc. On voit des personnes bien nourries avec des comptes identiques ... c'est jeter de l'huile sur le feu. L'impact de la chasse - La chasse est le privil\u00e8ge des riches et des puissants - 50:30<\/li>\n<li><strong>Nous devons vivre avec le monde \u00e9lectronique (virtuel)<\/strong> - must absolutely - 54:00<\/li>\n<li>La chasse peut-elle se permettre financi\u00e8rement de structurer quelque chose de mani\u00e8re efficace. Le budget marketing ne n\u00e9cessite que quelques % du chiffre d'affaires - 54:20<\/li>\n<li><strong>L'histoire de l'argent est un faux probl\u00e8me. <a title=\"Conf\u00e9rence sur la chasse \u00e0 Gargellen\" href=\"http:\/\/www.vjagd.at\/2013\/jagd-zwischen-hirschruf-und-twitter\/\" target=\"_blank\" rel=\"noopener\">Exemple de conf\u00e9rence sur la chasse \u00e0 Gargellen<\/a><\/strong> - 60:10<\/li>\n<li>exemple : <a title=\"Alexa Rank portail de chasse\" href=\"http:\/\/www.alexa.com\/siteinfo\/vjagd.at\" target=\"_blank\" rel=\"noopener\">Portail de chasse du Vorarlberg Classement Alexa Traffic Rank mondial 307 000e place<\/a>. En comparaison, Salzburger J\u00e4gerschaft place 8 206 000, Zentralstelle \u00d6sterreichischer J\u00e4gdverband 7 830 000, Jagd Bayern 1 234 000 - 61:10<\/li>\n<li>D'autres associations d\u00e9pensent une grande partie de leurs revenus dans des campagnes publiques - 64:00<\/li>\n<li><strong>Le classement 300.000 pour le portail de chasse du Vorarlberg est excellent<\/strong> - R\u00e9gion touristique de Gastein 126.000 avec des millions \u00e0 2 chiffres - 65:00<\/li>\n<li>Le choix n'est pas donn\u00e9 aux personnes d\u00e9ligitim\u00e9es - seulement montrer ou ne pas montrer - 67:00<\/li>\n<li>Nous d\u00e9pensons pr\u00e8s de 40% du budget pour les relations publiques - 68:30<\/li>\n<li>Le site <strong>Le probl\u00e8me n'est pas l'argent, c'est la fa\u00e7on de penser<\/strong>\u00a0 -7 millions de chasseurs en Europe - 72:50<\/li>\n<li>\u00c0 Salzbourg, il existe un concept de relations publiques - <strong>il serait important de se regrouper avec les autres associations de chasseurs<\/strong> - 76:50<\/li>\n<li>Le portail de chasse du Vorarlberg atteint les visiteurs \/ les personnes au-del\u00e0 des fronti\u00e8res - 80:40<\/li>\n<\/ul>\n<p><iframe style=\"border-style: none;\" src=\"http:\/\/www.jagdundnatur.tv:80\/embedded_videoplayer.php?episodeId=160\" width=\"640\" height=\"360\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe><\/p>","protected":false},"excerpt":{"rendered":"<p>CONSEIL : Enregistrement remarquable Jagd und Natur TV : Chasse et public - Le silence dans la for\u00eat ? <\/p>","protected":false},"author":2,"featured_media":8646,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[177],"tags":[181,182],"class_list":["post-6631","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","tag-jagd-und-natur-tv","tag-jagdtalk"],"_links":{"self":[{"href":"https:\/\/ddoptics.shop\/fr\/wp-json\/wp\/v2\/posts\/6631","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ddoptics.shop\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ddoptics.shop\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ddoptics.shop\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/ddoptics.shop\/fr\/wp-json\/wp\/v2\/comments?post=6631"}],"version-history":[{"count":0,"href":"https:\/\/ddoptics.shop\/fr\/wp-json\/wp\/v2\/posts\/6631\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ddoptics.shop\/fr\/wp-json\/wp\/v2\/media\/8646"}],"wp:attachment":[{"href":"https:\/\/ddoptics.shop\/fr\/wp-json\/wp\/v2\/media?parent=6631"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ddoptics.shop\/fr\/wp-json\/wp\/v2\/categories?post=6631"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ddoptics.shop\/fr\/wp-json\/wp\/v2\/tags?post=6631"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}