{"id":25185,"date":"2021-11-12T09:35:05","date_gmt":"2021-11-12T08:35:05","guid":{"rendered":"https:\/\/ddoptics.shop\/?post_type=product&#038;p=25185"},"modified":"2024-06-26T17:16:42","modified_gmt":"2024-06-26T15:16:42","slug":"pirschler-range-10x45-sable","status":"publish","type":"product","link":"https:\/\/ddoptics.shop\/fr\/kaufen\/pirschler-range-10x45-sand\/","title":{"rendered":"Pirschler Range 10\u00d745 Jumelles | avec t\u00e9l\u00e9m\u00e8tre laser | Couleur sable | DDoptics"},"content":{"rendered":"<div class=\"row\"  id=\"row-923606201\">\n\n\t<div id=\"col-292588767\" class=\"col medium-8 small-12 large-8\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<div>\n<h2>DDOPTICS PIRSCHLER RANGE 10\u00d745 | GAZ LONGUE DISTANCE AVEC T\u00c9L\u00c9M\u00c8TRE LASER | SABLE<\/h2>\n<p>Les nouveaux <strong>Gamme de jumelles 10\u00d745<\/strong> avec des t\u00e9l\u00e9m\u00e8tres performants posent de nouveaux jalons chez DDoptics. Rapport de la <a href=\"https:\/\/ddoptics.shop\/fr\/pirschler-range-10x45-jumelles-hubana-foire\/\" target=\"_blank\" rel=\"noopener\">Foire HUBANA \u00e0 lire.<\/a><\/p>\n<p>Un coup d'\u0153il \u00e0 travers les <strong>NOUVELLES jumelles Range<\/strong> avec <a href=\"https:\/\/de.wikipedia.org\/wiki\/Elektrooptische_Entfernungsmessung\" target=\"_blank\" rel=\"noopener sponsored\">T\u00e9l\u00e9m\u00e8tre<\/a> vous donne simplement une certitude d\u00e9finitive :<\/p>\n<blockquote><p><strong>PLUS de r\u00e9solution d'image, PLUS de\u00a0<span class=\"glossary-tooltip glossary-term-22858\" tabindex=\"0\"><span class=\"glossary-link\">Transmission de la lumi\u00e8re<\/span><\/span>, PLUS de port\u00e9e de mesure !<\/strong><\/p><\/blockquote>\n<\/div>\n<div class=\"product--description\">\n<h3>Jumelles Range 10\u00d745 - la plus haute r\u00e9solution de l'optique des jumelles<\/h3>\n<p>Comme aucune autre jumelle avec t\u00e9l\u00e9m\u00e8tre laser, les Range <strong>syst\u00e8me optique ED super lumineux avec prismes d'Abbe - K\u00f6nig<\/strong> sont combin\u00e9s. Les objectifs apochromatiques entra\u00eenent une correction presque totale du daltonisme dans l'image visible.<\/p>\n<p><strong>Lumi\u00e8re diffuse<\/strong> et les aberrations chromatiques sont \u00e9limin\u00e9es gr\u00e2ce \u00e0 l'utilisation de proc\u00e9d\u00e9s et d'outils sophistiqu\u00e9s. <strong>des mat\u00e9riaux de la plus haute qualit\u00e9<\/strong> presque enti\u00e8rement supprim\u00e9e.<\/p>\n<p>Ne pas se contenter de voir loin. Avec la Pirschler Range et un champ de vision de 114 m, tout ce qui est important reste visible.<\/p>\n<h3>Jumelles Range 10\u00d745 Syst\u00e8me de t\u00e9l\u00e9m\u00e9trie laser - port\u00e9e et pr\u00e9cision sup\u00e9rieures \u00e0 la moyenne<\/h3>\n<p>Avec un<strong> laser puls\u00e9 sophistiqu\u00e9<\/strong> permettent de r\u00e9aliser des port\u00e9es de mesure allant jusqu'\u00e0 3 km. Il faut toutefois tenir compte du fait que la port\u00e9e formelle d\u00e9pend de conditions ext\u00e9rieures, telles que la <strong>la temp\u00e9rature de l'air, le mirage ou la r\u00e9flectivit\u00e9<\/strong> de la cible.<\/p>\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-292588767 > .col-inner {\n  margin: 0px 0px -30px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n<\/div>\n\n\t<div id=\"col-1872648544\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1058250144\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1058250144 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_272526794\">\n\t\t<a class=\"\" href=\"https:\/\/www.shop.ddoptics.de\/garantiebestimmungen\" target=\"_blank\" rel=\"noopener\">\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img decoding=\"async\" width=\"352\" height=\"160\" src=\"https:\/\/ddoptics.shop\/wp-content\/uploads\/2014\/09\/DDoptics-Garantie.jpg\" class=\"attachment-large size-large\" alt=\"Garantie DDoptics\" srcset=\"https:\/\/ddoptics.shop\/wp-content\/uploads\/2014\/09\/DDoptics-Garantie.jpg 352w, https:\/\/ddoptics.shop\/wp-content\/uploads\/2014\/09\/DDoptics-Garantie-304x138.jpg 304w, https:\/\/ddoptics.shop\/wp-content\/uploads\/2014\/09\/DDoptics-Garantie-305x139.jpg 305w, https:\/\/ddoptics.shop\/wp-content\/uploads\/2014\/09\/DDoptics-Garantie-250x114.jpg 250w\" sizes=\"(max-width: 352px) 100vw, 352px\" title=\"\">\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/a>\t\t\n<style>\n#image_272526794 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n<h3>Jumelles DDoptics Range 10\u00d745 Facts<\/h3>\n\n\t\t<div class=\"icon-box featured-box icon-box-left text-left\"  >\n\t\t\t\t\t<div class=\"icon-box-img\" style=\"width: 32px\">\n\t\t\t\t<div class=\"icon\">\n\t\t\t\t\t<div class=\"icon-inner\" >\n\t\t\t\t\t\t<img decoding=\"async\" width=\"100\" height=\"83\" src=\"https:\/\/ddoptics.shop\/wp-content\/uploads\/2021\/11\/Pirschler-Range-klein.jpg\" class=\"attachment-medium size-medium\" alt=\"\" title=\"\">\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<div class=\"icon-box-text last-reset\">\n\t\t\t\t\t\t\t\t\t\n<p><span data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;\u2705&quot;}\" data-sheets-userformat=\"{&quot;2&quot;:15297,&quot;3&quot;:{&quot;1&quot;:0},&quot;9&quot;:0,&quot;10&quot;:2,&quot;11&quot;:0,&quot;12&quot;:0,&quot;14&quot;:{&quot;1&quot;:2,&quot;2&quot;:0},&quot;15&quot;:&quot;Calibri, sans-serif&quot;,&quot;16&quot;:11}\">\u2705 couleur sable<\/span><span style=\"color: #333333;\">\u00a0Armature<\/span><\/p>\n\t\t<\/div>\n\t<\/div>\n\t\n\t\n\n\t\t<div class=\"icon-box featured-box icon-box-left text-left\"  >\n\t\t\t\t\t<div class=\"icon-box-img\" style=\"width: 32px\">\n\t\t\t\t<div class=\"icon\">\n\t\t\t\t\t<div class=\"icon-inner\" >\n\t\t\t\t\t\t<img decoding=\"async\" width=\"100\" height=\"83\" src=\"https:\/\/ddoptics.shop\/wp-content\/uploads\/2021\/11\/Pirschler-Range-klein.jpg\" class=\"attachment-medium size-medium\" alt=\"\" title=\"\">\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<div class=\"icon-box-text last-reset\">\n\t\t\t\t\t\t\t\t\t\n<p>\u2705 Molette de mise au point et dioptre s\u00e9par\u00e9 en m\u00e9tal<\/p>\n\t\t<\/div>\n\t<\/div>\n\t\n\t\n\n\t\t<div class=\"icon-box featured-box icon-box-left text-left\"  >\n\t\t\t\t\t<div class=\"icon-box-img\" style=\"width: 32px\">\n\t\t\t\t<div class=\"icon\">\n\t\t\t\t\t<div class=\"icon-inner\" >\n\t\t\t\t\t\t<img decoding=\"async\" width=\"100\" height=\"83\" src=\"https:\/\/ddoptics.shop\/wp-content\/uploads\/2021\/11\/Pirschler-Range-klein.jpg\" class=\"attachment-medium size-medium\" alt=\"\" title=\"\">\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<div class=\"icon-box-text last-reset\">\n\t\t\t\t\t\t\t\t\t\n<p>\u2705 \u0152illetons avec trames claires<\/p>\n\t\t<\/div>\n\t<\/div>\n\t\n\t\n\n\t\t<div class=\"icon-box featured-box icon-box-left text-left\"  >\n\t\t\t\t\t<div class=\"icon-box-img\" style=\"width: 32px\">\n\t\t\t\t<div class=\"icon\">\n\t\t\t\t\t<div class=\"icon-inner\" >\n\t\t\t\t\t\t<img decoding=\"async\" width=\"100\" height=\"83\" src=\"https:\/\/ddoptics.shop\/wp-content\/uploads\/2021\/11\/Pirschler-Range-klein.jpg\" class=\"attachment-medium size-medium\" alt=\"\" title=\"\">\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<div class=\"icon-box-text last-reset\">\n\t\t\t\t\t\t\t\t\t\n<p>\u2705 Prismes d'Abbe-K\u00f6nig<\/p>\n\t\t<\/div>\n\t<\/div>\n\t\n\t\n\n\t\t<div class=\"icon-box featured-box icon-box-left text-left\"  >\n\t\t\t\t\t<div class=\"icon-box-img\" style=\"width: 32px\">\n\t\t\t\t<div class=\"icon\">\n\t\t\t\t\t<div class=\"icon-inner\" >\n\t\t\t\t\t\t<img decoding=\"async\" width=\"100\" height=\"83\" src=\"https:\/\/ddoptics.shop\/wp-content\/uploads\/2021\/11\/Pirschler-Range-klein.jpg\" class=\"attachment-medium size-medium\" alt=\"\" title=\"\">\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<div class=\"icon-box-text last-reset\">\n\t\t\t\t\t\t\t\t\t\n<p>\u2705 Concept de design Best Grip pour l'antid\u00e9rapance<\/p>\n\t\t<\/div>\n\t<\/div>\n\t\n\t\n\n\t\t<div class=\"icon-box featured-box icon-box-left text-left\"  >\n\t\t\t\t\t<div class=\"icon-box-img\" style=\"width: 32px\">\n\t\t\t\t<div class=\"icon\">\n\t\t\t\t\t<div class=\"icon-inner\" >\n\t\t\t\t\t\t<img decoding=\"async\" width=\"100\" height=\"83\" src=\"https:\/\/ddoptics.shop\/wp-content\/uploads\/2021\/11\/Pirschler-Range-klein.jpg\" class=\"attachment-medium size-medium\" alt=\"\" title=\"\">\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<div class=\"icon-box-text last-reset\">\n\t\t\t\t\t\t\t\t\t\n<p>\u2705 une des jumelles les plus lumineuses de sa cat\u00e9gorie<\/p>\n\t\t<\/div>\n\t<\/div>\n\t\n\t\n<div class=\"is-divider divider clearfix\" ><\/div>\n<a class=\"button white expand\" style=\"border-radius:10px;\">\n\t<i class=\"icon-angle-down\" aria-hidden=\"true\"><\/i>\t<span>T\u00e9l\u00e9charger le mode d'emploi<\/span>\n\t<\/a>\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n<p>Ainsi, chez <strong>40 degr\u00e9s de chaleur et un air fortement scintillant<\/strong> il n'est possible d'atteindre que des distances maximales de 1200 \u00e0 1500 m. Les meilleures port\u00e9es peuvent \u00eatre atteintes \u00e0 des temp\u00e9ratures allant jusqu'\u00e0 20 degr\u00e9s sur un b\u00e2timent en b\u00e9ton.<\/p>\n<p>Avec les Pirschler Range 10\u00d745 de couleur sable, c'est super simple <strong>Distances jusqu'\u00e0 2 900 m<\/strong> de saisir les donn\u00e9es. Il suffit de viser avec le marqueur dans le champ de vision et d'appuyer sur un bouton pour d\u00e9terminer la distance et l'angle.<\/p>\n<p>La mesure au laser est extr\u00eamement r\u00e9active et g\u00e8re une plage de temp\u00e9ratures proche de z\u00e9ro. <strong>une port\u00e9e incroyable.<\/strong> La reconnaissance automatique et <strong>Conversion de l'angle d'inclinaison<\/strong> indique la distance balistique pertinente sur l'\u00e9cran.<\/p>\n<p>Le site <strong>Le corps des jumelles est, gr\u00e2ce au magn\u00e9sium<\/strong> exceptionnellement robuste et parfaitement adapt\u00e9e \u00e0 toutes les situations sur le terrain. L'excellente dur\u00e9e de vie de la pile fait du changement de pile un \"\u00e9v\u00e9nement\" rare.<\/p>\n<h3>Caract\u00e9ristiques des jumelles Range 10\u00d745<\/h3>\n<ul>\n<li>L'affichage de la mesure de distance peut \u00eatre finement att\u00e9nu\u00e9 sur plusieurs niveaux. Ainsi, l'affichage peut toujours \u00eatre parfaitement adapt\u00e9 \u00e0 la situation d'\u00e9clairage.<\/li>\n<li>La distance peut \u00eatre affich\u00e9e seule ou avec une \u00e9querre ou la distance balistique en tenant compte de l'angle d'attaque.<\/li>\n<li>L'unit\u00e9 de mesure peut \u00eatre convertie de m\u00e8tres en yards.<\/li>\n<li>En maintenant le bouton de mesure enfonc\u00e9, il est possible de r\u00e9aliser une mesure de distance continue.<\/li>\n<\/ul>\n<h3>Jumelles Range \u00e9tanches : antibu\u00e9e et mise au point \u00e0 partir de 2,5 m<\/h3>\n<p>La mise au point des jumelles Range 10\u00d742 fonctionne \u00e0 partir d'une distance de 2,5 m\u00e8tres.<\/p>\n<p>Cela fonctionne m\u00eame sous la plus forte pluie, qui n'est pas dangereuse pour les jumelles. Un\u00a0<strong>Remplissage d'azote<\/strong> garantit que les jumelles Range sont enti\u00e8rement \u00e9tanches et antibu\u00e9e.<\/p>\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1533294940\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img decoding=\"async\" width=\"1020\" height=\"340\" src=\"https:\/\/ddoptics.shop\/wp-content\/uploads\/2021\/11\/DDoptics-Range.jpg\" class=\"attachment-large size-large\" alt=\"Jumelles DDoptics Range 10x45\" srcset=\"https:\/\/ddoptics.shop\/wp-content\/uploads\/2021\/11\/DDoptics-Range.jpg 1200w, https:\/\/ddoptics.shop\/wp-content\/uploads\/2021\/11\/DDoptics-Range-304x101.jpg 304w, https:\/\/ddoptics.shop\/wp-content\/uploads\/2021\/11\/DDoptics-Range-305x102.jpg 305w, https:\/\/ddoptics.shop\/wp-content\/uploads\/2021\/11\/DDoptics-Range-632x211.jpg 632w, https:\/\/ddoptics.shop\/wp-content\/uploads\/2021\/11\/DDoptics-Range-800x267.jpg 800w, https:\/\/ddoptics.shop\/wp-content\/uploads\/2021\/11\/DDoptics-Range-510x170.jpg 510w, https:\/\/ddoptics.shop\/wp-content\/uploads\/2021\/11\/DDoptics-Range-250x83.jpg 250w\" sizes=\"(max-width: 1020px) 100vw, 1020px\" title=\"\">\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"caption\">Jumelles DDoptics Range 10x45<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1533294940 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n<div class=\"text-center\"><div class=\"is-divider divider clearfix\" style=\"margin-top:2.0em;margin-bottom:2.0em;max-width:50%;\"><\/div><\/div>\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_948877987\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_948877987 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n<h3>L'innovation des jumelles DDoptics Range<\/h3>\n<div class=\"row\"  id=\"row-1740837959\">\n\n\t<div id=\"col-222069532\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\" style=\"background-color:rgb(34, 34, 34);\" >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1556890228\">\n\t\t<a class=\"image-lightbox lightbox-gallery\" title=\"\" href=\"https:\/\/ddoptics.shop\/wp-content\/uploads\/2021\/11\/Range-Fernglas.jpg\">\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img decoding=\"async\" width=\"584\" height=\"406\" src=\"https:\/\/ddoptics.shop\/wp-content\/uploads\/2021\/11\/Range-Fernglas.jpg\" class=\"attachment-large size-large\" alt=\"Jumelles DDoptics Range avec laser\" srcset=\"https:\/\/ddoptics.shop\/wp-content\/uploads\/2021\/11\/Range-Fernglas.jpg 584w, https:\/\/ddoptics.shop\/wp-content\/uploads\/2021\/11\/Range-Fernglas-304x211.jpg 304w, https:\/\/ddoptics.shop\/wp-content\/uploads\/2021\/11\/Range-Fernglas-305x212.jpg 305w, https:\/\/ddoptics.shop\/wp-content\/uploads\/2021\/11\/Range-Fernglas-510x355.jpg 510w, https:\/\/ddoptics.shop\/wp-content\/uploads\/2021\/11\/Range-Fernglas-250x174.jpg 250w\" sizes=\"(max-width: 584px) 100vw, 584px\" title=\"\">\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"caption\">Jumelles DDoptics Range avec laser<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/a>\t\t\n<style>\n#image_1556890228 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-50195436\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<ul>\n<li>Avec une port\u00e9e allant jusqu'\u00e0 2 900 m, les Pirscher Range 10\u00d745 sont l'une des jumelles les plus performantes de leur cat\u00e9gorie.<\/li>\n<li>Prismes d'Abbe-K\u00f6nig sur une jumelle avec mesure laser<\/li>\n<li>Les objectifs apochromatiques permettent une correction presque compl\u00e8te de l'aberration chromatique.<\/li>\n<\/ul>\n<div class=\"row\"  id=\"row-1054065674\">\n\n\t<div id=\"col-1988205431\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner text-left dark\"  >\n\t\t\t\n\t\t\t\n<ul>\n<li>L'exp\u00e9rience avec les <strong>NOUVELLES jumelles Range<\/strong>\u00a0vous donne simplement une certitude d\u00e9finitive :<br \/>\n<blockquote><p><strong>PLUS de r\u00e9solution d'image, PLUS de\u00a0<span class=\"glossary-tooltip glossary-term-22858\" tabindex=\"0\"><span class=\"glossary-link\">Transmission de la lumi\u00e8re<\/span><\/span>, PLUS de port\u00e9e de mesure !<\/strong><\/p><\/blockquote>\n<\/li>\n<\/ul>\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1988205431 > .col-inner {\n  margin: 0px 0px -30px 0px;\n  border-radius: 10px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n<style>\n#row-1054065674 > .col > .col-inner {\n  padding: 15px 0px 1px 0px;\n  background-color: rgb(196, 113, 58);\n  border-radius: 10px;\n}\n<\/style>\n<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n<div class=\"text-center\"><div class=\"is-divider divider clearfix\" style=\"margin-top:2.0em;margin-bottom:2.0em;max-width:50%;\"><\/div><\/div>\n<h2><span style=\"font-size: 90%;\">L'\u00e9quipe de DDoptics est compos\u00e9e d'innovateurs g\u00e9niaux qui allument aussi votre feu !<\/span><\/h2>\n<p>Le site <strong>DDoptics Optische Ger\u00e4te &amp; Feinwerktechnik KG (Appareils optiques et technique de pr\u00e9cision)<\/strong>Fond\u00e9e en 2007, l'entreprise est sp\u00e9cialis\u00e9e dans le d\u00e9veloppement et la distribution d'appareils et d'instruments opto\u00e9lectroniques.<\/p>\n<p>Le portefeuille de produits comprend <strong>Jumelles, longues-vues, lunettes de vis\u00e9e et appareils de vision nocturne<\/strong> pour une utilisation professionnelle.<\/p>\n<p>Des d\u00e9veloppements innovants et une qualit\u00e9 sup\u00e9rieure pour un rapport qualit\u00e9-prix in\u00e9gal\u00e9 convainquent de plus en plus de personnes. <strong>Amoureux de la nature, chasseur,\u00a0<span class=\"glossary-tooltip glossary-term-22811\" tabindex=\"0\"><span class=\"glossary-link\">Ornithologues<\/span><\/span> et les amateurs de plein air.<\/strong><\/p>\n\t<div id=\"gap-279895467\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-279895467 {\n  padding-top: 20px;\n}\n<\/style>\n\t<\/div>\n\t\n\n\t<section class=\"section info-card-1 has-mask mask-angled\" id=\"section_1117443565\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\t<div id=\"gap-171567902\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-171567902 {\n  padding-top: 30px;\n}\n<\/style>\n\t<\/div>\n\t\n<div class=\"row row-small align-equal\"  id=\"row-1875778382\">\n\n\t<div id=\"col-144945293\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"box has-hover   has-hover box-push box-text-bottom\" >\n\n\t\t<div class=\"box-image\" style=\"border-radius:5%;\">\n\t\t\t<a href=\"#\" >\t\t\t<div class=\"image-zoom image-cover\" style=\"padding-top:100%;\">\n\t\t\t\t<img decoding=\"async\" width=\"884\" height=\"1040\" src=\"https:\/\/ddoptics.shop\/wp-content\/uploads\/2021\/11\/Pirschler-Range-10x45-stehe.jpg\" class=\"attachment- size-\" alt=\"\" srcset=\"https:\/\/ddoptics.shop\/wp-content\/uploads\/2021\/11\/Pirschler-Range-10x45-stehe.jpg 884w, https:\/\/ddoptics.shop\/wp-content\/uploads\/2021\/11\/Pirschler-Range-10x45-stehe-304x358.jpg 304w, https:\/\/ddoptics.shop\/wp-content\/uploads\/2021\/11\/Pirschler-Range-10x45-stehe-305x360.jpg 305w, https:\/\/ddoptics.shop\/wp-content\/uploads\/2021\/11\/Pirschler-Range-10x45-stehe-632x744.jpg 632w, https:\/\/ddoptics.shop\/wp-content\/uploads\/2021\/11\/Pirschler-Range-10x45-stehe-680x800.jpg 680w, https:\/\/ddoptics.shop\/wp-content\/uploads\/2021\/11\/Pirschler-Range-10x45-stehe-510x600.jpg 510w, https:\/\/ddoptics.shop\/wp-content\/uploads\/2021\/11\/Pirschler-Range-10x45-stehe-213x250.jpg 213w\" sizes=\"(max-width: 884px) 100vw, 884px\" title=\"\">\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/a>\t\t<\/div>\n\n\t\t<div class=\"box-text text-center\" style=\"background-color:rgb(255, 255, 255);padding:20px 5px 19px 5px;\">\n\t\t\t<div class=\"box-text-inner\">\n\t\t\t\t\n<h3>Le poids de la Pirschler Range 10\u00d745<\/h3>\n<p>Malgr\u00e9 sa technique compacte, le Pirschler Range convainc par son poids de 1018 g seulement.<\/p>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-144945293 > .col-inner {\n  border-radius: 10px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-1289746479\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"box has-hover   has-hover box-push box-text-bottom\" >\n\n\t\t<div class=\"box-image\" style=\"border-radius:5%;\">\n\t\t\t<a href=\"#\" >\t\t\t<div class=\"image-zoom image-cover\" style=\"padding-top:100%;\">\n\t\t\t\t<img decoding=\"async\" width=\"884\" height=\"1040\" src=\"https:\/\/ddoptics.shop\/wp-content\/uploads\/2021\/11\/Pirschler-Range-10x45-1.jpg\" class=\"attachment- size-\" alt=\"Pirschler Range 10x45 Jumelles avec t\u00e9l\u00e9m\u00e8tre\" srcset=\"https:\/\/ddoptics.shop\/wp-content\/uploads\/2021\/11\/Pirschler-Range-10x45-1.jpg 884w, https:\/\/ddoptics.shop\/wp-content\/uploads\/2021\/11\/Pirschler-Range-10x45-1-304x358.jpg 304w, https:\/\/ddoptics.shop\/wp-content\/uploads\/2021\/11\/Pirschler-Range-10x45-1-305x360.jpg 305w, https:\/\/ddoptics.shop\/wp-content\/uploads\/2021\/11\/Pirschler-Range-10x45-1-632x744.jpg 632w, https:\/\/ddoptics.shop\/wp-content\/uploads\/2021\/11\/Pirschler-Range-10x45-1-680x800.jpg 680w, https:\/\/ddoptics.shop\/wp-content\/uploads\/2021\/11\/Pirschler-Range-10x45-1-510x600.jpg 510w, https:\/\/ddoptics.shop\/wp-content\/uploads\/2021\/11\/Pirschler-Range-10x45-1-213x250.jpg 213w\" sizes=\"(max-width: 884px) 100vw, 884px\" title=\"\">\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/a>\t\t<\/div>\n\n\t\t<div class=\"box-text text-center\" style=\"background-color:rgb(255, 255, 255);padding:20px 5% 20px 5%;\">\n\t\t\t<div class=\"box-text-inner\">\n\t\t\t\t\n<h3>La transmission lumineuse du verre<\/h3>\n<p>Nouvelle exp\u00e9rience visuelle gr\u00e2ce \u00e0 une transmission lumineuse TOP + brillance, contraste et luminosit\u00e9 des couleurs maximales.<\/p>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1289746479 > .col-inner {\n  border-radius: 10px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-1008028815\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"box has-hover   has-hover box-push box-text-bottom\" >\n\n\t\t<div class=\"box-image\" style=\"border-radius:5%;\">\n\t\t\t<a href=\"#\" >\t\t\t<div class=\"image-zoom image-cover\" style=\"padding-top:100%;\">\n\t\t\t\t<img decoding=\"async\" width=\"552\" height=\"553\" src=\"https:\/\/ddoptics.shop\/wp-content\/uploads\/2021\/11\/Bedienelemente-Range.jpg\" class=\"attachment- size-\" alt=\"El\u00e9ments de commande des jumelles Pirschler Range 10x45\" srcset=\"https:\/\/ddoptics.shop\/wp-content\/uploads\/2021\/11\/Bedienelemente-Range.jpg 552w, https:\/\/ddoptics.shop\/wp-content\/uploads\/2021\/11\/Bedienelemente-Range-304x305.jpg 304w, https:\/\/ddoptics.shop\/wp-content\/uploads\/2021\/11\/Bedienelemente-Range-305x306.jpg 305w, https:\/\/ddoptics.shop\/wp-content\/uploads\/2021\/11\/Bedienelemente-Range-510x511.jpg 510w, https:\/\/ddoptics.shop\/wp-content\/uploads\/2021\/11\/Bedienelemente-Range-340x340.jpg 340w, https:\/\/ddoptics.shop\/wp-content\/uploads\/2021\/11\/Bedienelemente-Range-250x250.jpg 250w\" sizes=\"(max-width: 552px) 100vw, 552px\" title=\"\">\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/a>\t\t<\/div>\n\n\t\t<div class=\"box-text text-center\" style=\"background-color:rgb(255, 255, 255);padding:20px 5% 20px 5%;\">\n\t\t\t<div class=\"box-text-inner\">\n\t\t\t\t\n<h3>L'armature des jumelles<\/h3>\n<p>Concept de design Best Grip pour des propri\u00e9t\u00e9s antid\u00e9rapantes extr\u00eames.<\/p>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1008028815 > .col-inner {\n  border-radius: 10px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n<style>\n#row-1875778382 > .col > .col-inner {\n  background-color: rgb(255,255,255);\n}\n<\/style>\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1117443565 {\n  padding-top: 15px;\n  padding-bottom: 15px;\n  background-color: rgb(224, 224, 224);\n}\n<\/style>\n\t<\/section>\n\t\n\t<div id=\"gap-380445159\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-380445159 {\n  padding-top: 29px;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_115323113\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_115323113 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\t<section class=\"section\" id=\"section_330730111\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row align-center\"  id=\"row-1156034970\">\n\n\t<div id=\"col-703225694\" class=\"col medium-5 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner text-left\"  >\n\t\t\t\n\t\t\t\n<h3><span style=\"font-size: 300%; color: #c47100;\">Jumelles<\/span><span style=\"font-size: 300%; color: #f4bf1e;\"><br \/>\n<\/span><\/h3>\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-703225694 > .col-inner {\n  padding: 0px 0px 0px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-868288447\" class=\"col medium-7 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner text-left\"  >\n\t\t\t\n\t\t\t\n<p class=\"lead\">Des jumelles de haute qualit\u00e9 font de l'observation de la nature une exp\u00e9rience visuelle ultime. Passer du temps en plein air et vivre de nombreuses exp\u00e9riences est aussi une forme de plaisir.<\/p>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n<div class=\"row\"  id=\"row-1659430339\">\n\n\t<div id=\"col-2046710576\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n<p><span style=\"font-size: 150%;\">DDoptics Range 10\u00d745 R\u00e9solution<\/span><\/p>\n<p>Quelle est la nettet\u00e9 de l'image ? Nous d\u00e9finissons la nettet\u00e9 de l'image en 10 niveaux, de 0 (flou) \u00e0 10 (extr\u00eame).<\/p>\n<p><span style=\"color: #53a600; font-size: 500%;\"><span class=\"count-up\">9<\/span>\/10<\/span><\/p>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-779211460\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n<p><span style=\"font-size: 150%;\">DDoptics Range Transmission de la lumi\u00e8re<\/span><\/p>\n<p>Quelle est la puissance lumineuse ? Nous d\u00e9finissons 10 niveaux de 0 (faible) \u00e0 10 (m\u00e9ga)<\/p>\n<p><span style=\"color: #53a600; font-size: 500%;\"><span class=\"count-up\">9<\/span>\/10<\/span><\/p>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-175501109\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n<p><span style=\"font-size: 150%;\">Jumelles DDoptics Range facteur de plaisir<\/span><\/p>\n<p>Quel est le degr\u00e9 de plaisir des jumelles ? Nous d\u00e9finissons le facteur de plaisir de 1 (plut\u00f4t fade) \u00e0 12 (super g\u00e9nial).<\/p>\n<p><span style=\"color: #53a600; font-size: 500%;\"><span class=\"count-up\">12<\/span>\/12<\/span><\/p>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_330730111 {\n  padding-top: 0px;\n  padding-bottom: 0px;\n}\n<\/style>\n\t<\/section>\n\t\n<div class=\"text-center\"><div class=\"is-divider divider clearfix\" style=\"margin-top:2.0em;margin-bottom:2.0em;max-width:50%;\"><\/div><\/div>\n\n\t<section class=\"section dark has-parallax\" id=\"section_562401868\">\n\t\t<div class=\"section-bg fill\" data-parallax-container=\".section\" data-parallax-background data-parallax=\"-3\">\n\t\t\t\t\t\t\t\t\t<div class=\"section-bg-overlay absolute fill\"><\/div>\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row\"  id=\"row-1248819632\">\n\n\t<div id=\"col-198122681\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<h2>A lire - Consid\u00e9rations pour l'achat de jumelles<\/h2>\n<div class=\"accordion\">\n\t<div id=\"accordion-558132690\" class=\"accordion-item\">\n\t\t<a id=\"accordion-558132690-label\" class=\"accordion-title plain active\" href=\"#accordion-item-die-wahl-des-richtigen-fernglases?\" aria-expanded=\"true\" aria-controls=\"accordion-558132690-content\">\n\t\t\t<button class=\"toggle\" aria-label=\"Basculer\"><i class=\"icon-angle-down\" aria-hidden=\"true\"><\/i><\/button>\n\t\t\t<span>Choisir les bonnes jumelles ?<\/span>\n\t\t<\/a>\n\t\t<div id=\"accordion-558132690-content\" class=\"accordion-inner\" style=\"display: block;\" aria-labelledby=\"accordion-558132690-label\">\n\t\t\t\n<p>Pour\u00a0<strong>de plus en plus de personnes passionn\u00e9es par la nature<\/strong>\u00a0a d\u00e9cid\u00e9 d'acqu\u00e9rir un\u00a0<strong>des jumelles de haute qualit\u00e9<\/strong>\u00a0de bonnes raisons :<\/p>\n<ul>\n<li>Une paire de jumelles permet\u00a0<strong>des observations beaucoup plus profondes<\/strong>\u00a0- surtout des d\u00e9tails. Certains objets sont accompagn\u00e9s de\u00a0<strong>de bonnes jumelles qu'\u00e0 l'\u0153il nu.\u00a0<span class=\"glossary-tooltip glossary-term-22824\" tabindex=\"0\"><span class=\"glossary-link\">\u0152il<\/span><\/span>!<\/strong><\/li>\n<li>De nombreuses personnes ont besoin de jumelles pour une utilisation sp\u00e9cifique. Par exemple, l'ornithologue pour les\u00a0<span class=\"glossary-tooltip glossary-term-22811\" tabindex=\"0\"><span class=\"glossary-link\">Observation des oiseaux<\/span><\/span>. Les jumelles peuvent en outre \u00eatre utilis\u00e9es de mani\u00e8re polyvalente (par ex. pour l'observation de la nature et des paysages).<\/li>\n<li>Pour beaucoup, une superbe paire de jumelles devient\u00a0<strong>compagnon de vie permanent<\/strong><\/li>\n<\/ul>\n<p>Selon nous, les\u00a0<strong>Les crit\u00e8res suivants sont importants pour le choix des jumelles :<\/strong><\/p>\n<ul>\n<li>Poids<\/li>\n<li>Jumelles\u00a0<span class=\"glossary-tooltip glossary-term-22891\" tabindex=\"0\"><span class=\"glossary-link\">Agrandissement<\/span><\/span><\/li>\n<li>Intensit\u00e9 lumineuse des jumelles<\/li>\n<li>Champ de vision<\/li>\n<li><strong>Pupille de sortie<\/strong><\/li>\n<\/ul>\n<p>Ces sujets font l'objet de nombreuses discussions philosophiques. Mais justement, il y a deux effets oppos\u00e9s :<\/p>\n<ul>\n<li>Sur le site\u00a0<strong>En montagne, dans les Alpes ou en randonn\u00e9e, un verre doit \u00eatre aussi petit ou l\u00e9ger que possible.<\/strong>\u00a0- c'est \u00e9vident !<\/li>\n<li>Mais \u00e0 peine arriv\u00e9 \u00e0 destination, on a un l\u00e9ger tremblement dans les bras (les muscles ont \u00e9t\u00e9 sollicit\u00e9s et le pouls est encore \u00e9lev\u00e9). Est-ce que c'est\u00a0<strong>verre plus lourd, on peut le tenir plus calmement en raison de l'inertie de masse.<\/strong>\u00a0La masse plus \u00e9lev\u00e9e du verre r\u00e9agit plus lentement aux vibrations transmises.<\/li>\n<\/ul>\n\t\t<\/div>\n\t<\/div>\n\t\n\t<div id=\"accordion-3913380552\" class=\"accordion-item\">\n\t\t<a id=\"accordion-3913380552-label\" class=\"accordion-title plain\" href=\"#accordion-item-optische-verg\u00fctung-bei-ferngl\u00e4sern-\u2013-eine-wissenschaft-f\u00fcr-sich\" aria-expanded=\"false\" aria-controls=\"accordion-3913380552-content\">\n\t\t\t<button class=\"toggle\" aria-label=\"Basculer\"><i class=\"icon-angle-down\" aria-hidden=\"true\"><\/i><\/button>\n\t\t\t<span>Le traitement optique des jumelles - une science en soi<\/span>\n\t\t<\/a>\n\t\t<div id=\"accordion-3913380552-content\" class=\"accordion-inner\" aria-labelledby=\"accordion-3913380552-label\">\n\t\t\t\n<p>Le site\u00a0<strong><span class=\"glossary-tooltip glossary-term-22909\" tabindex=\"0\"><span class=\"glossary-link\">Rev\u00eatement<\/span><\/span>\u00a0ou r\u00e9mun\u00e9ration<\/strong>\u00a0d'une lentille est co\u00fbteux et tr\u00e8s\u00a0<strong>une grande influence sur la qualit\u00e9 optique de l'optique et sur le prix.<\/strong><\/p>\n<p>En particulier ici, les\u00a0<strong>grandes diff\u00e9rences<\/strong>\u00a0entre les bonnes et les moyennes jumelles est visible - sp\u00e9cialement pour les\u00a0<strong>Luminosit\u00e9, contraste et brillance de l'image.<\/strong><\/p>\n<p>Un\u00a0<strong><span class=\"glossary-tooltip glossary-term-22878\" tabindex=\"0\"><span class=\"glossary-link\">Objectif<\/span><\/span>\u00a0respectivement\u00a0<span class=\"glossary-tooltip glossary-term-22918\" tabindex=\"0\"><span class=\"glossary-link\">Prisme<\/span><\/span><\/strong>\u00a0se compose de plusieurs\u00a0<span class=\"glossary-tooltip glossary-term-22709\" tabindex=\"0\"><span class=\"glossary-link\">Lentilles<\/span><\/span>\u00a0ce qui fait que certains\u00a0<span class=\"glossary-tooltip glossary-term-22905\" tabindex=\"0\"><span class=\"glossary-link\">Verre<\/span><\/span>\u00a0air dans des jumelles. Cela conduit \u00e0\u00a0<strong>Lumi\u00e8re diffuse et perte de lumi\u00e8re<\/strong>. Par\u00a0<strong><span class=\"glossary-tooltip glossary-term-22755\" tabindex=\"0\"><span class=\"glossary-link\">Rev\u00eatements<\/span><\/span>\u00a0les pertes de lumi\u00e8re sont r\u00e9duites<\/strong>\u00a0et la quantit\u00e9 de lumi\u00e8re qui atteint vos yeux est augment\u00e9e.<\/p>\n<p>Dans le cas d'un objectif \u00e0 rev\u00eatements multiples, les lentilles sont dot\u00e9es de plusieurs couches de rev\u00eatement.<\/p>\n<p>Ce rev\u00eatement multiple, ou \"multi coating\", est utilis\u00e9 pour les optiques de haute qualit\u00e9 afin d'obtenir des images plus lumineuses et plus contrast\u00e9es.<\/p>\n<p>Outre les propri\u00e9t\u00e9s optiques, les propri\u00e9t\u00e9s m\u00e9caniques du coating sont \u00e9galement importantes.<\/p>\n<figure id=\"attachment_10045\" class=\"wp-caption alignright\" aria-describedby=\"caption-attachment-10045\"><figcaption id=\"caption-attachment-10045\" class=\"wp-caption-text\"><\/figcaption><\/figure>\n<h3>Rev\u00eatements anti-adh\u00e9rents pour les jumelles<\/h3>\n<p>Le site\u00a0<strong>Mod\u00e8les haut de gamme\u00a0<\/strong>de la plupart<strong>\u00a0Jumelles Fabricant\u00a0<\/strong>disposent de<strong>\u00a0Traitements hydrofuges et antisalissure\u00a0<\/strong>sur les ext\u00e9rieurs<strong>\u00a0pi\u00e8ces de lentilles,\u00a0<\/strong>ce qui fait que<strong>\u00a0<span class=\"glossary-tooltip glossary-term-22939\" tabindex=\"0\"><span class=\"glossary-link\">Eau<\/span><\/span>\u00a0d\u00e9perle facilement\u00a0<\/strong>et que le nettoyage est facilit\u00e9 en cas de salissures.<\/p>\n<p>Les fabricants de jumelles ont d\u00e9velopp\u00e9 pour ces\u00a0<strong>Nano rev\u00eatements<\/strong>\u00a0des d\u00e9signations ou des brevets propres, comme par exemple<\/p>\n<ul>\n<li><strong>LotuTec<\/strong>\u00a0chez Zeiss<\/li>\n<li>Raindefender Nano Protection (RNP) chez DDoptics<\/li>\n<li><strong>AquaDura<\/strong>\u00a0chez Leica<\/li>\n<li><strong>Swaroclean<\/strong>\u00a0chez Swarovski<\/li>\n<li><strong>Nano-Protection<\/strong>\u00a0chez Steiner<\/li>\n<\/ul>\n<p>Sp\u00e9cialement pour le\u00a0<strong>Nettoyer les jumelles<\/strong>\u00a0doit \u00eatre<strong>\u00a0a veill\u00e9 \u00e0\u00a0<\/strong>seront<strong>Il est important de ne pas endommager le rev\u00eatement.<\/strong><\/p>\n\t\t<\/div>\n\t<\/div>\n\t\n\t<div id=\"accordion-1925281892\" class=\"accordion-item\">\n\t\t<a id=\"accordion-1925281892-label\" class=\"accordion-title plain\" href=\"#accordion-item-objektivdurchmesser-und-vergr\u00f6sserung-bei-ferngl\u00e4sern\" aria-expanded=\"false\" aria-controls=\"accordion-1925281892-content\">\n\t\t\t<button class=\"toggle\" aria-label=\"Basculer\"><i class=\"icon-angle-down\" aria-hidden=\"true\"><\/i><\/button>\n\t\t\t<span>Diam\u00e8tre de l'objectif et grossissement des jumelles<\/span>\n\t\t<\/a>\n\t\t<div id=\"accordion-1925281892-content\" class=\"accordion-inner\" aria-labelledby=\"accordion-1925281892-label\">\n\t\t\t\n<p>Le site\u00a0<strong>la plupart des chasseurs<\/strong>\u00a0vont le\u00a0<strong>t\u00f4t le matin, en fin d'apr\u00e8s-midi ou en d\u00e9but de soir\u00e9e<\/strong> \u00e0 la chasse.<\/p>\n<p>Pendant cette p\u00e9riode, la\u00a0<strong>Intensit\u00e9 lumineuse de leur verre de chasse, \u00e0 la premi\u00e8re ou \u00e0 la derni\u00e8re lumi\u00e8re<\/strong>La question de l'acc\u00e8s \u00e0 l'information\u00a0<strong>images lumineuses ans\u00a0<span class=\"glossary-tooltip glossary-term-22824\" tabindex=\"0\"><span class=\"glossary-link\">\u0152il<\/span><\/span><\/strong>\u00a0\u00e0 livrer.<\/p>\n<p>Les jumelles de chasse courantes pour la chasse \u00e0 l'approche et la chasse en mouvement ont un\u00a0<span class=\"glossary-tooltip glossary-term-22895\" tabindex=\"0\"><span class=\"glossary-link\">Diam\u00e8tre de l'objectif<\/span><\/span> autour de 42 mm, car \u00e0 ce diam\u00e8tre d'objectif, le poids est encore confortable<\/p>\n<h3>Le grossissement id\u00e9al des jumelles est de l'ordre de 8 \u00e0 10 fois.<\/h3>\n<p><strong>Important :<\/strong>\u00a0Le site\u00a0<strong>Le facteur d'agrandissement a un effet n\u00e9gatif sur l'intensit\u00e9 lumineuse des jumelles de chasse !<\/strong>\u00a0C'est pour cette raison que la plupart des chasseurs\u00a0<strong>Jumelles avec <a href=\"https:\/\/ddoptics.shop\/fr\/boutique\/jumelles\/grossissement-jumelles\/8x-augmentation\/\" target=\"_blank\" rel=\"noopener\" data-schema-attribute=\"\">8x<\/a> ou <a href=\"https:\/\/ddoptics.shop\/fr\/boutique\/jumelles\/grossissement-jumelles\/10x-augmentation\/\" target=\"_blank\" rel=\"noopener\" data-schema-attribute=\"\">10x<\/a> Pr\u00e9f\u00e9rer l'agrandissement.<\/strong><\/p>\n<p>En r\u00e8gle g\u00e9n\u00e9rale, les grossissements des jumelles jusqu'\u00e0 10x ne posent aucun probl\u00e8me.<\/p>\n<p><strong>A partir d'un 10x\u00a0<span class=\"glossary-tooltip glossary-term-22891\" tabindex=\"0\"><span class=\"glossary-link\">Agrandissement<\/span><\/span>\u00a0des jumelles<\/strong>\u00a0est, en raison de la<strong>\u00a0un grossissement optique plus \u00e9lev\u00e9<\/strong>\u00a0d\u00e9j\u00e0 une<strong>\u00a0main immobile n\u00e9cessaire en raison du \"boug\u00e9\" de l'image.<\/strong><\/p>\n<p>Le grossissement des jumelles a \u00e9galement une influence sur la taille de l'image.\u00a0<span class=\"glossary-tooltip glossary-term-22726\" tabindex=\"0\"><span class=\"glossary-link\">Pupille de sortie<\/span><\/span>Il faut donc en tenir compte lors du choix de l'optique !<\/p>\n\t\t<\/div>\n\t<\/div>\n\t\n\t<div id=\"accordion-2806939173\" class=\"accordion-item\">\n\t\t<a id=\"accordion-2806939173-label\" class=\"accordion-title plain\" href=\"#accordion-item-auswahl-eines-idealen-fernglas-f\u00fcr-die-vogelbeobachtung\" aria-expanded=\"false\" aria-controls=\"accordion-2806939173-content\">\n\t\t\t<button class=\"toggle\" aria-label=\"Basculer\"><i class=\"icon-angle-down\" aria-hidden=\"true\"><\/i><\/button>\n\t\t\t<span>Choisir les jumelles id\u00e9ales pour l'observation des oiseaux<\/span>\n\t\t<\/a>\n\t\t<div id=\"accordion-2806939173-content\" class=\"accordion-inner\" aria-labelledby=\"accordion-2806939173-label\">\n\t\t\t\n<p>D'embl\u00e9e - chez\u00a0<strong>Observateurs d'oiseaux<\/strong>\u00a0c'est une question de d\u00e9tails et d'importance\u00a0<strong>Exigences en mati\u00e8re de qualit\u00e9 d'image.<\/strong><\/p>\n<figure id=\"attachment_1808\" class=\"wp-caption alignright\" aria-describedby=\"caption-attachment-1808\"><figcaption id=\"caption-attachment-1808\" class=\"wp-caption-text\">\u00a0<\/figcaption><\/figure>\n<p>Le site\u00a0<strong>Exigences relatives aux jumelles pour\u00a0<span class=\"glossary-tooltip glossary-term-22811\" tabindex=\"0\"><span class=\"glossary-link\">Observation des oiseaux<\/span><\/span>\u00a0<\/strong>sont g\u00e9n\u00e9ralement<strong>\u00a0plus \u00e9lev\u00e9 que celui d'un\u00a0<em>Jumelles de voyage<\/em>.<\/strong><\/p>\n<p>Pour que les ornithologues puissent profiter de la \"sensation d'\u00eatre au c\u0153ur de l'action\" avec des jumelles, il faut satisfaire aux exigences les plus \u00e9lev\u00e9es en mati\u00e8re de brillance des couleurs et des images, de nettet\u00e9 des contrastes et de pr\u00e9cision des d\u00e9tails.<\/p>\n<p>Lorsqu'un oiseau particulier est assis devant soi dans la nature, on veut le voir dans toute sa splendeur.<\/p>\n<p>Pour cette raison, il faut pour <strong>ornithologie une paire de jumelles performante avec\u00a0<em>une grande brillance d'image et une grande fid\u00e9lit\u00e9 des couleurs.<\/em><\/strong><\/p>\n<p>Un bon\u00a0<strong>Jumelles pour l'observation des oiseaux<\/strong>\u00a0permet une observation de pr\u00e8s riche en couleurs et en contrastes, ce qui\u00a0<strong>de d\u00e9tails et de percevoir le jeu de couleurs du plumage.<\/strong>\u00a0peut \u00eatre.<\/p>\n<p>Le site <span class=\"glossary-tooltip glossary-term-22891\" tabindex=\"0\"><span class=\"glossary-link\">Agrandissement<\/span><\/span>\u00a08x et 10x est un bon compromis et l'exp\u00e9rience montre que c'est le choix le plus fr\u00e9quent de la plupart des amateurs d'oiseaux.<\/p>\n\t\t<\/div>\n\t<\/div>\n\t\n<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_562401868 {\n  padding-top: 20px;\n  padding-bottom: 20px;\n}\n#section_562401868 .section-bg-overlay {\n  background-color: rgba(0, 0, 0, 0.7);\n}\n<\/style>\n\t<\/section>","protected":false},"excerpt":{"rendered":"<p><img decoding=\"async\" class=\"alignnone wp-image-10471 size-full\" title=\"Chasse \u00e0 l&#039;approche\" src=\"https:\/\/ddoptics.shop\/wp-content\/uploads\/2016\/04\/Ansitz-Jagd.jpg\" alt=\"Chasse \u00e0 l&#039;approche\" width=\"50\" height=\"50\" \/><a href=\"https:\/\/ddoptics.shop\/wp-content\/uploads\/2016\/04\/Bergwandern-klein.jpg\"><img decoding=\"async\" class=\"alignnone size-full wp-image-10180\" src=\"https:\/\/ddoptics.shop\/wp-content\/uploads\/2016\/04\/Bergwandern-klein.jpg\" alt=\"Jumelles de randonn\u00e9e en montagne\" width=\"50\" height=\"50\" \/><\/a><a href=\"https:\/\/ddoptics.shop\/wp-content\/uploads\/2016\/09\/Wandern-klein.jpg\"><img decoding=\"async\" class=\"alignnone size-full wp-image-10174\" src=\"https:\/\/ddoptics.shop\/wp-content\/uploads\/2016\/09\/Wandern-klein.jpg\" alt=\"Jumelles de randonn\u00e9e Treckking\" width=\"50\" height=\"50\" \/><\/a><a href=\"https:\/\/ddoptics.shop\/wp-content\/uploads\/2016\/09\/Ornitologie-klein.jpg\"><img decoding=\"async\" class=\"alignnone size-full wp-image-10170\" src=\"https:\/\/ddoptics.shop\/wp-content\/uploads\/2016\/09\/Ornitologie-klein.jpg\" alt=\"Observation des oiseaux\" width=\"50\" height=\"50\" \/><\/a><br \/>\nJumelles universelles les plus lumineuses de leur cat\u00e9gorie - avec prismes Abbe-K\u00f6nig et super mesure laser. Les nouvelles jumelles super claires et indestructibles pour les observateurs exigeants - DDoptics Pirschler Range 10\u00d745.<\/p>","protected":false},"featured_media":25175,"comment_status":"open","ping_status":"closed","template":"","meta":{"inline_featured_image":false,"footnotes":""},"product_brand":[],"product_cat":[351,746,949,345,344,1083,354],"product_tag":[748,78,321,1080],"class_list":{"0":"post-25185","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-10x-vergroesserung","7":"product_cat-45-mm-objektiv","8":"product_cat-messeaktion","9":"product_cat-jagd-und-wild","10":"product_cat-naturbeobachtung","11":"product_cat-pirschler-range","12":"product_cat-vogelbeobachtung","13":"product_tag-10x45-fernglas","14":"product_tag-ddoptics","15":"product_tag-laserentfernungsmesser","16":"product_tag-range-10x45","17":"product_shipping_class-paket","18":"pa_brand-marke-ddoptics","19":"pa_farbe-sand","20":"pa_produkt-typ-fernglas","22":"first","23":"outofstock","24":"sale","25":"taxable","26":"shipping-taxable","27":"purchasable","28":"product-type-simple"},"bundled_by":["25831","25858","25854"],"bundle_stock_status":"outofstock","bundle_stock_quantity":null,"bundle_virtual":false,"bundle_layout":"","bundle_add_to_cart_form_location":"","bundle_editable_in_cart":false,"bundle_sold_individually_context":"","bundle_item_grouping":"","bundle_min_size":"","bundle_max_size":"","bundle_price":[],"bundled_items":[],"bundle_sell_ids":[],"_links":{"self":[{"href":"https:\/\/ddoptics.shop\/fr\/wp-json\/wp\/v2\/product\/25185","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ddoptics.shop\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/ddoptics.shop\/fr\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/ddoptics.shop\/fr\/wp-json\/wp\/v2\/comments?post=25185"}],"version-history":[{"count":4,"href":"https:\/\/ddoptics.shop\/fr\/wp-json\/wp\/v2\/product\/25185\/revisions"}],"predecessor-version":[{"id":26239,"href":"https:\/\/ddoptics.shop\/fr\/wp-json\/wp\/v2\/product\/25185\/revisions\/26239"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ddoptics.shop\/fr\/wp-json\/wp\/v2\/media\/25175"}],"wp:attachment":[{"href":"https:\/\/ddoptics.shop\/fr\/wp-json\/wp\/v2\/media?parent=25185"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/ddoptics.shop\/fr\/wp-json\/wp\/v2\/product_brand?post=25185"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/ddoptics.shop\/fr\/wp-json\/wp\/v2\/product_cat?post=25185"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/ddoptics.shop\/fr\/wp-json\/wp\/v2\/product_tag?post=25185"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}